{"id":4169,"date":"2021-01-21T18:04:00","date_gmt":"2021-01-21T15:04:00","guid":{"rendered":"http:\/\/serifos.gr\/?p=4169"},"modified":"2021-01-26T18:06:00","modified_gmt":"2021-01-26T15:06:00","slug":"%cf%80%cf%81%ce%bf%cf%83%ce%ba%ce%bb%ce%b7%cf%83%ce%b7-3%ce%bf%cf%85-%ce%b4%ce%b7%ce%bc%ce%bf%cf%84%ce%b9%ce%ba%ce%bf%cf%85-%cf%83%cf%85%ce%bc%ce%b2%ce%bf%cf%85%ce%bb%ce%b9%ce%bf%cf%85","status":"publish","type":"post","link":"https:\/\/serifos.gr\/fr\/%cf%80%cf%81%ce%bf%cf%83%ce%ba%ce%bb%ce%b7%cf%83%ce%b7-3%ce%bf%cf%85-%ce%b4%ce%b7%ce%bc%ce%bf%cf%84%ce%b9%ce%ba%ce%bf%cf%85-%cf%83%cf%85%ce%bc%ce%b2%ce%bf%cf%85%ce%bb%ce%b9%ce%bf%cf%85\/","title":{"rendered":"\u03a0\u03a1\u039f\u03a3\u039a\u039b\u0397\u03a3\u0397 3\u03bf\u03c5 \u0394\u0397\u039c\u039f\u03a4\u0399\u039a\u039f\u03a5 \u03a3\u03a5\u039c\u0392\u039f\u03a5\u039b\u0399\u039f\u03a5"},"content":{"rendered":"<div class=\"wp-block-pdfemb-pdf-embedder-viewer\"><a href=\"https:\/\/serifos.gr\/wp-content\/uploads\/2021\/01\/\u03a0\u03a1\u039f\u03a3\u039a\u039b\u0397\u03a3\u0397-3\u03bf\u03c5-\u0394\u03a3.pdf\" class=\"pdfemb-viewer\" style=\"\" data-width=\"max\" data-height=\"max\" data-toolbar=\"bottom\" data-toolbar-fixed=\"off\">\u03a0\u03a1\u039f\u03a3\u039a\u039b\u0397\u03a3\u0397-3\u03bf\u03c5-\u0394\u03a3<\/a><\/div>\n<p class=\"wp-block-pdfemb-pdf-embedder-viewer\"><\/p>","protected":false},"excerpt":{"rendered":"","protected":false},"author":2,"featured_media":0,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_monsterinsights_skip_tracking":false,"footnotes":"","_links_to":"","_links_to_target":""},"categories":[79],"tags":[],"class_list":["post-4169","post","type-post","status-publish","format-standard","hentry","category-proskliseis_dimotikou_symvouliou"],"aioseo_notices":[],"aioseo_head":"\n\t\t<!-- All in One SEO 5.0.0.1 - aioseo.com -->\n\t<meta name=\"description\" content=\"\u03a0\u03a1\u039f\u03a3\u039a\u039b\u0397\u03a3\u0397-3\u03bf\u03c5-\u0394\u03a3\" \/>\n\t<meta name=\"robots\" content=\"max-image-preview:large\" \/>\n\t<meta name=\"author\" content=\"Stelios Livanios\"\/>\n\t<link rel=\"canonical\" href=\"https:\/\/serifos.gr\/fr\/%cf%80%cf%81%ce%bf%cf%83%ce%ba%ce%bb%ce%b7%cf%83%ce%b7-3%ce%bf%cf%85-%ce%b4%ce%b7%ce%bc%ce%bf%cf%84%ce%b9%ce%ba%ce%bf%cf%85-%cf%83%cf%85%ce%bc%ce%b2%ce%bf%cf%85%ce%bb%ce%b9%ce%bf%cf%85\/\" \/>\n\t<meta name=\"generator\" content=\"All in One SEO (AIOSEO) 5.0.0.1\" \/>\n\t\t<meta property=\"og:locale\" content=\"fr_FR\" \/>\n\t\t<meta property=\"og:site_name\" content=\"Serifos.gr - \u0399\u03c3\u03c4\u03bf\u03c3\u03b5\u03bb\u03af\u03b4\u03b1 \u0394\u03ae\u03bc\u03bf\u03c5 \u03a3\u03b5\u03c1\u03af\u03c6\u03bf\u03c5\" \/>\n\t\t<meta property=\"og:type\" content=\"article\" \/>\n\t\t<meta property=\"og:title\" content=\"\u03a0\u03a1\u039f\u03a3\u039a\u039b\u0397\u03a3\u0397 3\u03bf\u03c5 \u0394\u0397\u039c\u039f\u03a4\u0399\u039a\u039f\u03a5 \u03a3\u03a5\u039c\u0392\u039f\u03a5\u039b\u0399\u039f\u03a5 - Serifos.gr\" \/>\n\t\t<meta property=\"og:description\" content=\"\u03a0\u03a1\u039f\u03a3\u039a\u039b\u0397\u03a3\u0397-3\u03bf\u03c5-\u0394\u03a3\" \/>\n\t\t<meta property=\"og:url\" content=\"https:\/\/serifos.gr\/fr\/%cf%80%cf%81%ce%bf%cf%83%ce%ba%ce%bb%ce%b7%cf%83%ce%b7-3%ce%bf%cf%85-%ce%b4%ce%b7%ce%bc%ce%bf%cf%84%ce%b9%ce%ba%ce%bf%cf%85-%cf%83%cf%85%ce%bc%ce%b2%ce%bf%cf%85%ce%bb%ce%b9%ce%bf%cf%85\/\" \/>\n\t\t<meta property=\"og:image\" content=\"https:\/\/serifos.gr\/wp-content\/uploads\/2017\/08\/Logo_final.png\" \/>\n\t\t<meta property=\"og:image:secure_url\" content=\"https:\/\/serifos.gr\/wp-content\/uploads\/2017\/08\/Logo_final.png\" \/>\n\t\t<meta property=\"og:image:width\" content=\"181\" \/>\n\t\t<meta property=\"og:image:height\" content=\"46\" \/>\n\t\t<meta property=\"article:published_time\" content=\"2021-01-21T15:04:00+00:00\" \/>\n\t\t<meta property=\"article:modified_time\" content=\"2021-01-26T15:06:00+00:00\" \/>\n\t\t<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/dimosserifou\/\" \/>\n\t\t<meta name=\"twitter:card\" content=\"summary\" \/>\n\t\t<meta name=\"twitter:title\" content=\"\u03a0\u03a1\u039f\u03a3\u039a\u039b\u0397\u03a3\u0397 3\u03bf\u03c5 \u0394\u0397\u039c\u039f\u03a4\u0399\u039a\u039f\u03a5 \u03a3\u03a5\u039c\u0392\u039f\u03a5\u039b\u0399\u039f\u03a5 - Serifos.gr\" \/>\n\t\t<meta name=\"twitter:description\" content=\"\u03a0\u03a1\u039f\u03a3\u039a\u039b\u0397\u03a3\u0397-3\u03bf\u03c5-\u0394\u03a3\" \/>\n\t\t<meta name=\"twitter:image\" content=\"https:\/\/serifos.gr\/wp-content\/uploads\/2017\/08\/Logo_final.png\" \/>\n\t\t<script type=\"application\/ld+json\" class=\"aioseo-schema\">\n\t\t\t{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"BlogPosting\",\"@id\":\"https:\\\/\\\/serifos.gr\\\/fr\\\/%cf%80%cf%81%ce%bf%cf%83%ce%ba%ce%bb%ce%b7%cf%83%ce%b7-3%ce%bf%cf%85-%ce%b4%ce%b7%ce%bc%ce%bf%cf%84%ce%b9%ce%ba%ce%bf%cf%85-%cf%83%cf%85%ce%bc%ce%b2%ce%bf%cf%85%ce%bb%ce%b9%ce%bf%cf%85\\\/#blogposting\",\"name\":\"\\u03a0\\u03a1\\u039f\\u03a3\\u039a\\u039b\\u0397\\u03a3\\u0397 3\\u03bf\\u03c5 \\u0394\\u0397\\u039c\\u039f\\u03a4\\u0399\\u039a\\u039f\\u03a5 \\u03a3\\u03a5\\u039c\\u0392\\u039f\\u03a5\\u039b\\u0399\\u039f\\u03a5 - Serifos.gr\",\"headline\":\"\\u03a0\\u03a1\\u039f\\u03a3\\u039a\\u039b\\u0397\\u03a3\\u0397 3\\u03bf\\u03c5 \\u0394\\u0397\\u039c\\u039f\\u03a4\\u0399\\u039a\\u039f\\u03a5 \\u03a3\\u03a5\\u039c\\u0392\\u039f\\u03a5\\u039b\\u0399\\u039f\\u03a5\",\"author\":{\"@id\":\"https:\\\/\\\/serifos.gr\\\/fr\\\/author\\\/nslivanios\\\/#author\"},\"publisher\":{\"@id\":\"https:\\\/\\\/serifos.gr\\\/fr\\\/#organization\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/serifos.gr\\\/wp-content\\\/uploads\\\/2017\\\/08\\\/Logo_final.png\",\"@id\":\"https:\\\/\\\/serifos.gr\\\/fr\\\/#articleImage\",\"width\":181,\"height\":46},\"datePublished\":\"2021-01-21T18:04:00+03:00\",\"dateModified\":\"2021-01-26T18:06:00+03:00\",\"inLanguage\":\"fr-FR\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/serifos.gr\\\/fr\\\/%cf%80%cf%81%ce%bf%cf%83%ce%ba%ce%bb%ce%b7%cf%83%ce%b7-3%ce%bf%cf%85-%ce%b4%ce%b7%ce%bc%ce%bf%cf%84%ce%b9%ce%ba%ce%bf%cf%85-%cf%83%cf%85%ce%bc%ce%b2%ce%bf%cf%85%ce%bb%ce%b9%ce%bf%cf%85\\\/#webpage\"},\"isPartOf\":{\"@id\":\"https:\\\/\\\/serifos.gr\\\/fr\\\/%cf%80%cf%81%ce%bf%cf%83%ce%ba%ce%bb%ce%b7%cf%83%ce%b7-3%ce%bf%cf%85-%ce%b4%ce%b7%ce%bc%ce%bf%cf%84%ce%b9%ce%ba%ce%bf%cf%85-%cf%83%cf%85%ce%bc%ce%b2%ce%bf%cf%85%ce%bb%ce%b9%ce%bf%cf%85\\\/#webpage\"},\"articleSection\":\"\\u03a0\\u03c1\\u03bf\\u03c3\\u03ba\\u03bb\\u03ae\\u03c3\\u03b5\\u03b9\\u03c2 \\u0394\\u03b7\\u03bc\\u03bf\\u03c4\\u03b9\\u03ba\\u03bf\\u03cd \\u03a3\\u03c5\\u03bc\\u03b2\\u03bf\\u03c5\\u03bb\\u03af\\u03bf\\u03c5\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/serifos.gr\\\/fr\\\/%cf%80%cf%81%ce%bf%cf%83%ce%ba%ce%bb%ce%b7%cf%83%ce%b7-3%ce%bf%cf%85-%ce%b4%ce%b7%ce%bc%ce%bf%cf%84%ce%b9%ce%ba%ce%bf%cf%85-%cf%83%cf%85%ce%bc%ce%b2%ce%bf%cf%85%ce%bb%ce%b9%ce%bf%cf%85\\\/#breadcrumblist\",\"itemListElement\":[{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/serifos.gr\\\/fr#listItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/serifos.gr\\\/fr\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/serifos.gr\\\/fr\\\/category\\\/proskliseis_dimotikou_symvouliou\\\/#listItem\",\"name\":\"\\u03a0\\u03c1\\u03bf\\u03c3\\u03ba\\u03bb\\u03ae\\u03c3\\u03b5\\u03b9\\u03c2 \\u0394\\u03b7\\u03bc\\u03bf\\u03c4\\u03b9\\u03ba\\u03bf\\u03cd \\u03a3\\u03c5\\u03bc\\u03b2\\u03bf\\u03c5\\u03bb\\u03af\\u03bf\\u03c5\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/serifos.gr\\\/fr\\\/category\\\/proskliseis_dimotikou_symvouliou\\\/#listItem\",\"position\":2,\"name\":\"\\u03a0\\u03c1\\u03bf\\u03c3\\u03ba\\u03bb\\u03ae\\u03c3\\u03b5\\u03b9\\u03c2 \\u0394\\u03b7\\u03bc\\u03bf\\u03c4\\u03b9\\u03ba\\u03bf\\u03cd \\u03a3\\u03c5\\u03bc\\u03b2\\u03bf\\u03c5\\u03bb\\u03af\\u03bf\\u03c5\",\"item\":\"https:\\\/\\\/serifos.gr\\\/fr\\\/category\\\/proskliseis_dimotikou_symvouliou\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/serifos.gr\\\/fr\\\/%cf%80%cf%81%ce%bf%cf%83%ce%ba%ce%bb%ce%b7%cf%83%ce%b7-3%ce%bf%cf%85-%ce%b4%ce%b7%ce%bc%ce%bf%cf%84%ce%b9%ce%ba%ce%bf%cf%85-%cf%83%cf%85%ce%bc%ce%b2%ce%bf%cf%85%ce%bb%ce%b9%ce%bf%cf%85\\\/#listItem\",\"name\":\"\\u03a0\\u03a1\\u039f\\u03a3\\u039a\\u039b\\u0397\\u03a3\\u0397 3\\u03bf\\u03c5 \\u0394\\u0397\\u039c\\u039f\\u03a4\\u0399\\u039a\\u039f\\u03a5 \\u03a3\\u03a5\\u039c\\u0392\\u039f\\u03a5\\u039b\\u0399\\u039f\\u03a5\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/serifos.gr\\\/fr#listItem\",\"name\":\"Home\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/serifos.gr\\\/fr\\\/%cf%80%cf%81%ce%bf%cf%83%ce%ba%ce%bb%ce%b7%cf%83%ce%b7-3%ce%bf%cf%85-%ce%b4%ce%b7%ce%bc%ce%bf%cf%84%ce%b9%ce%ba%ce%bf%cf%85-%cf%83%cf%85%ce%bc%ce%b2%ce%bf%cf%85%ce%bb%ce%b9%ce%bf%cf%85\\\/#listItem\",\"position\":3,\"name\":\"\\u03a0\\u03a1\\u039f\\u03a3\\u039a\\u039b\\u0397\\u03a3\\u0397 3\\u03bf\\u03c5 \\u0394\\u0397\\u039c\\u039f\\u03a4\\u0399\\u039a\\u039f\\u03a5 \\u03a3\\u03a5\\u039c\\u0392\\u039f\\u03a5\\u039b\\u0399\\u039f\\u03a5\",\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/serifos.gr\\\/fr\\\/category\\\/proskliseis_dimotikou_symvouliou\\\/#listItem\",\"name\":\"\\u03a0\\u03c1\\u03bf\\u03c3\\u03ba\\u03bb\\u03ae\\u03c3\\u03b5\\u03b9\\u03c2 \\u0394\\u03b7\\u03bc\\u03bf\\u03c4\\u03b9\\u03ba\\u03bf\\u03cd \\u03a3\\u03c5\\u03bc\\u03b2\\u03bf\\u03c5\\u03bb\\u03af\\u03bf\\u03c5\"}}]},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/serifos.gr\\\/fr\\\/#organization\",\"name\":\"Serifos.gr\",\"description\":\"\\u0399\\u03c3\\u03c4\\u03bf\\u03c3\\u03b5\\u03bb\\u03af\\u03b4\\u03b1 \\u0394\\u03ae\\u03bc\\u03bf\\u03c5 \\u03a3\\u03b5\\u03c1\\u03af\\u03c6\\u03bf\\u03c5\",\"url\":\"https:\\\/\\\/serifos.gr\\\/fr\\\/\",\"telephone\":\"+302281051210\",\"logo\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/serifos.gr\\\/wp-content\\\/uploads\\\/2017\\\/08\\\/Logo_final.png\",\"@id\":\"https:\\\/\\\/serifos.gr\\\/fr\\\/%cf%80%cf%81%ce%bf%cf%83%ce%ba%ce%bb%ce%b7%cf%83%ce%b7-3%ce%bf%cf%85-%ce%b4%ce%b7%ce%bc%ce%bf%cf%84%ce%b9%ce%ba%ce%bf%cf%85-%cf%83%cf%85%ce%bc%ce%b2%ce%bf%cf%85%ce%bb%ce%b9%ce%bf%cf%85\\\/#organizationLogo\",\"width\":181,\"height\":46},\"image\":{\"@id\":\"https:\\\/\\\/serifos.gr\\\/fr\\\/%cf%80%cf%81%ce%bf%cf%83%ce%ba%ce%bb%ce%b7%cf%83%ce%b7-3%ce%bf%cf%85-%ce%b4%ce%b7%ce%bc%ce%bf%cf%84%ce%b9%ce%ba%ce%bf%cf%85-%cf%83%cf%85%ce%bc%ce%b2%ce%bf%cf%85%ce%bb%ce%b9%ce%bf%cf%85\\\/#organizationLogo\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/dimosserifou\\\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/serifos.gr\\\/fr\\\/author\\\/nslivanios\\\/#author\",\"url\":\"https:\\\/\\\/serifos.gr\\\/fr\\\/author\\\/nslivanios\\\/\",\"name\":\"Stelios Livanios\",\"image\":{\"@type\":\"ImageObject\",\"@id\":\"https:\\\/\\\/serifos.gr\\\/fr\\\/%cf%80%cf%81%ce%bf%cf%83%ce%ba%ce%bb%ce%b7%cf%83%ce%b7-3%ce%bf%cf%85-%ce%b4%ce%b7%ce%bc%ce%bf%cf%84%ce%b9%ce%ba%ce%bf%cf%85-%cf%83%cf%85%ce%bc%ce%b2%ce%bf%cf%85%ce%bb%ce%b9%ce%bf%cf%85\\\/#authorImage\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/792605e3bbc86e998535857713ea857f9fd2f4916d59659513056a03e5d789f7?s=96&d=mm&r=g\",\"width\":96,\"height\":96,\"caption\":\"Stelios Livanios\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/serifos.gr\\\/fr\\\/%cf%80%cf%81%ce%bf%cf%83%ce%ba%ce%bb%ce%b7%cf%83%ce%b7-3%ce%bf%cf%85-%ce%b4%ce%b7%ce%bc%ce%bf%cf%84%ce%b9%ce%ba%ce%bf%cf%85-%cf%83%cf%85%ce%bc%ce%b2%ce%bf%cf%85%ce%bb%ce%b9%ce%bf%cf%85\\\/#webpage\",\"url\":\"https:\\\/\\\/serifos.gr\\\/fr\\\/%cf%80%cf%81%ce%bf%cf%83%ce%ba%ce%bb%ce%b7%cf%83%ce%b7-3%ce%bf%cf%85-%ce%b4%ce%b7%ce%bc%ce%bf%cf%84%ce%b9%ce%ba%ce%bf%cf%85-%cf%83%cf%85%ce%bc%ce%b2%ce%bf%cf%85%ce%bb%ce%b9%ce%bf%cf%85\\\/\",\"name\":\"\\u03a0\\u03a1\\u039f\\u03a3\\u039a\\u039b\\u0397\\u03a3\\u0397 3\\u03bf\\u03c5 \\u0394\\u0397\\u039c\\u039f\\u03a4\\u0399\\u039a\\u039f\\u03a5 \\u03a3\\u03a5\\u039c\\u0392\\u039f\\u03a5\\u039b\\u0399\\u039f\\u03a5 - Serifos.gr\",\"description\":\"\\u03a0\\u03a1\\u039f\\u03a3\\u039a\\u039b\\u0397\\u03a3\\u0397-3\\u03bf\\u03c5-\\u0394\\u03a3\",\"inLanguage\":\"fr-FR\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/serifos.gr\\\/fr\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/serifos.gr\\\/fr\\\/%cf%80%cf%81%ce%bf%cf%83%ce%ba%ce%bb%ce%b7%cf%83%ce%b7-3%ce%bf%cf%85-%ce%b4%ce%b7%ce%bc%ce%bf%cf%84%ce%b9%ce%ba%ce%bf%cf%85-%cf%83%cf%85%ce%bc%ce%b2%ce%bf%cf%85%ce%bb%ce%b9%ce%bf%cf%85\\\/#breadcrumblist\"},\"author\":{\"@id\":\"https:\\\/\\\/serifos.gr\\\/fr\\\/author\\\/nslivanios\\\/#author\"},\"creator\":{\"@id\":\"https:\\\/\\\/serifos.gr\\\/fr\\\/author\\\/nslivanios\\\/#author\"},\"datePublished\":\"2021-01-21T18:04:00+03:00\",\"dateModified\":\"2021-01-26T18:06:00+03:00\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/serifos.gr\\\/fr\\\/#website\",\"url\":\"https:\\\/\\\/serifos.gr\\\/fr\\\/\",\"name\":\"Serifos.gr\",\"description\":\"\\u0399\\u03c3\\u03c4\\u03bf\\u03c3\\u03b5\\u03bb\\u03af\\u03b4\\u03b1 \\u0394\\u03ae\\u03bc\\u03bf\\u03c5 \\u03a3\\u03b5\\u03c1\\u03af\\u03c6\\u03bf\\u03c5\",\"inLanguage\":\"fr-FR\",\"publisher\":{\"@id\":\"https:\\\/\\\/serifos.gr\\\/fr\\\/#organization\"}}]}\n\t\t<\/script>\n\t\t<!-- All in One SEO -->\n\n","aioseo_head_json":{"title":"\u03a0\u03a1\u039f\u03a3\u039a\u039b\u0397\u03a3\u0397 3\u03bf\u03c5 \u0394\u0397\u039c\u039f\u03a4\u0399\u039a\u039f\u03a5 \u03a3\u03a5\u039c\u0392\u039f\u03a5\u039b\u0399\u039f\u03a5 - Serifos.gr","description":"\u03a0\u03a1\u039f\u03a3\u039a\u039b\u0397\u03a3\u0397-3\u03bf\u03c5-\u0394\u03a3","canonical_url":"https:\/\/serifos.gr\/fr\/%cf%80%cf%81%ce%bf%cf%83%ce%ba%ce%bb%ce%b7%cf%83%ce%b7-3%ce%bf%cf%85-%ce%b4%ce%b7%ce%bc%ce%bf%cf%84%ce%b9%ce%ba%ce%bf%cf%85-%cf%83%cf%85%ce%bc%ce%b2%ce%bf%cf%85%ce%bb%ce%b9%ce%bf%cf%85\/","robots":"max-image-preview:large","keywords":"","webmasterTools":{"miscellaneous":""},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"BlogPosting","@id":"https:\/\/serifos.gr\/fr\/%cf%80%cf%81%ce%bf%cf%83%ce%ba%ce%bb%ce%b7%cf%83%ce%b7-3%ce%bf%cf%85-%ce%b4%ce%b7%ce%bc%ce%bf%cf%84%ce%b9%ce%ba%ce%bf%cf%85-%cf%83%cf%85%ce%bc%ce%b2%ce%bf%cf%85%ce%bb%ce%b9%ce%bf%cf%85\/#blogposting","name":"\u03a0\u03a1\u039f\u03a3\u039a\u039b\u0397\u03a3\u0397 3\u03bf\u03c5 \u0394\u0397\u039c\u039f\u03a4\u0399\u039a\u039f\u03a5 \u03a3\u03a5\u039c\u0392\u039f\u03a5\u039b\u0399\u039f\u03a5 - Serifos.gr","headline":"\u03a0\u03a1\u039f\u03a3\u039a\u039b\u0397\u03a3\u0397 3\u03bf\u03c5 \u0394\u0397\u039c\u039f\u03a4\u0399\u039a\u039f\u03a5 \u03a3\u03a5\u039c\u0392\u039f\u03a5\u039b\u0399\u039f\u03a5","author":{"@id":"https:\/\/serifos.gr\/fr\/author\/nslivanios\/#author"},"publisher":{"@id":"https:\/\/serifos.gr\/fr\/#organization"},"image":{"@type":"ImageObject","url":"https:\/\/serifos.gr\/wp-content\/uploads\/2017\/08\/Logo_final.png","@id":"https:\/\/serifos.gr\/fr\/#articleImage","width":181,"height":46},"datePublished":"2021-01-21T18:04:00+03:00","dateModified":"2021-01-26T18:06:00+03:00","inLanguage":"fr-FR","mainEntityOfPage":{"@id":"https:\/\/serifos.gr\/fr\/%cf%80%cf%81%ce%bf%cf%83%ce%ba%ce%bb%ce%b7%cf%83%ce%b7-3%ce%bf%cf%85-%ce%b4%ce%b7%ce%bc%ce%bf%cf%84%ce%b9%ce%ba%ce%bf%cf%85-%cf%83%cf%85%ce%bc%ce%b2%ce%bf%cf%85%ce%bb%ce%b9%ce%bf%cf%85\/#webpage"},"isPartOf":{"@id":"https:\/\/serifos.gr\/fr\/%cf%80%cf%81%ce%bf%cf%83%ce%ba%ce%bb%ce%b7%cf%83%ce%b7-3%ce%bf%cf%85-%ce%b4%ce%b7%ce%bc%ce%bf%cf%84%ce%b9%ce%ba%ce%bf%cf%85-%cf%83%cf%85%ce%bc%ce%b2%ce%bf%cf%85%ce%bb%ce%b9%ce%bf%cf%85\/#webpage"},"articleSection":"\u03a0\u03c1\u03bf\u03c3\u03ba\u03bb\u03ae\u03c3\u03b5\u03b9\u03c2 \u0394\u03b7\u03bc\u03bf\u03c4\u03b9\u03ba\u03bf\u03cd \u03a3\u03c5\u03bc\u03b2\u03bf\u03c5\u03bb\u03af\u03bf\u03c5"},{"@type":"BreadcrumbList","@id":"https:\/\/serifos.gr\/fr\/%cf%80%cf%81%ce%bf%cf%83%ce%ba%ce%bb%ce%b7%cf%83%ce%b7-3%ce%bf%cf%85-%ce%b4%ce%b7%ce%bc%ce%bf%cf%84%ce%b9%ce%ba%ce%bf%cf%85-%cf%83%cf%85%ce%bc%ce%b2%ce%bf%cf%85%ce%bb%ce%b9%ce%bf%cf%85\/#breadcrumblist","itemListElement":[{"@type":"ListItem","@id":"https:\/\/serifos.gr\/fr#listItem","position":1,"name":"Home","item":"https:\/\/serifos.gr\/fr","nextItem":{"@type":"ListItem","@id":"https:\/\/serifos.gr\/fr\/category\/proskliseis_dimotikou_symvouliou\/#listItem","name":"\u03a0\u03c1\u03bf\u03c3\u03ba\u03bb\u03ae\u03c3\u03b5\u03b9\u03c2 \u0394\u03b7\u03bc\u03bf\u03c4\u03b9\u03ba\u03bf\u03cd \u03a3\u03c5\u03bc\u03b2\u03bf\u03c5\u03bb\u03af\u03bf\u03c5"}},{"@type":"ListItem","@id":"https:\/\/serifos.gr\/fr\/category\/proskliseis_dimotikou_symvouliou\/#listItem","position":2,"name":"\u03a0\u03c1\u03bf\u03c3\u03ba\u03bb\u03ae\u03c3\u03b5\u03b9\u03c2 \u0394\u03b7\u03bc\u03bf\u03c4\u03b9\u03ba\u03bf\u03cd \u03a3\u03c5\u03bc\u03b2\u03bf\u03c5\u03bb\u03af\u03bf\u03c5","item":"https:\/\/serifos.gr\/fr\/category\/proskliseis_dimotikou_symvouliou\/","nextItem":{"@type":"ListItem","@id":"https:\/\/serifos.gr\/fr\/%cf%80%cf%81%ce%bf%cf%83%ce%ba%ce%bb%ce%b7%cf%83%ce%b7-3%ce%bf%cf%85-%ce%b4%ce%b7%ce%bc%ce%bf%cf%84%ce%b9%ce%ba%ce%bf%cf%85-%cf%83%cf%85%ce%bc%ce%b2%ce%bf%cf%85%ce%bb%ce%b9%ce%bf%cf%85\/#listItem","name":"\u03a0\u03a1\u039f\u03a3\u039a\u039b\u0397\u03a3\u0397 3\u03bf\u03c5 \u0394\u0397\u039c\u039f\u03a4\u0399\u039a\u039f\u03a5 \u03a3\u03a5\u039c\u0392\u039f\u03a5\u039b\u0399\u039f\u03a5"},"previousItem":{"@type":"ListItem","@id":"https:\/\/serifos.gr\/fr#listItem","name":"Home"}},{"@type":"ListItem","@id":"https:\/\/serifos.gr\/fr\/%cf%80%cf%81%ce%bf%cf%83%ce%ba%ce%bb%ce%b7%cf%83%ce%b7-3%ce%bf%cf%85-%ce%b4%ce%b7%ce%bc%ce%bf%cf%84%ce%b9%ce%ba%ce%bf%cf%85-%cf%83%cf%85%ce%bc%ce%b2%ce%bf%cf%85%ce%bb%ce%b9%ce%bf%cf%85\/#listItem","position":3,"name":"\u03a0\u03a1\u039f\u03a3\u039a\u039b\u0397\u03a3\u0397 3\u03bf\u03c5 \u0394\u0397\u039c\u039f\u03a4\u0399\u039a\u039f\u03a5 \u03a3\u03a5\u039c\u0392\u039f\u03a5\u039b\u0399\u039f\u03a5","previousItem":{"@type":"ListItem","@id":"https:\/\/serifos.gr\/fr\/category\/proskliseis_dimotikou_symvouliou\/#listItem","name":"\u03a0\u03c1\u03bf\u03c3\u03ba\u03bb\u03ae\u03c3\u03b5\u03b9\u03c2 \u0394\u03b7\u03bc\u03bf\u03c4\u03b9\u03ba\u03bf\u03cd \u03a3\u03c5\u03bc\u03b2\u03bf\u03c5\u03bb\u03af\u03bf\u03c5"}}]},{"@type":"Organization","@id":"https:\/\/serifos.gr\/fr\/#organization","name":"Serifos.gr","description":"\u0399\u03c3\u03c4\u03bf\u03c3\u03b5\u03bb\u03af\u03b4\u03b1 \u0394\u03ae\u03bc\u03bf\u03c5 \u03a3\u03b5\u03c1\u03af\u03c6\u03bf\u03c5","url":"https:\/\/serifos.gr\/fr\/","telephone":"+302281051210","logo":{"@type":"ImageObject","url":"https:\/\/serifos.gr\/wp-content\/uploads\/2017\/08\/Logo_final.png","@id":"https:\/\/serifos.gr\/fr\/%cf%80%cf%81%ce%bf%cf%83%ce%ba%ce%bb%ce%b7%cf%83%ce%b7-3%ce%bf%cf%85-%ce%b4%ce%b7%ce%bc%ce%bf%cf%84%ce%b9%ce%ba%ce%bf%cf%85-%cf%83%cf%85%ce%bc%ce%b2%ce%bf%cf%85%ce%bb%ce%b9%ce%bf%cf%85\/#organizationLogo","width":181,"height":46},"image":{"@id":"https:\/\/serifos.gr\/fr\/%cf%80%cf%81%ce%bf%cf%83%ce%ba%ce%bb%ce%b7%cf%83%ce%b7-3%ce%bf%cf%85-%ce%b4%ce%b7%ce%bc%ce%bf%cf%84%ce%b9%ce%ba%ce%bf%cf%85-%cf%83%cf%85%ce%bc%ce%b2%ce%bf%cf%85%ce%bb%ce%b9%ce%bf%cf%85\/#organizationLogo"},"sameAs":["https:\/\/www.facebook.com\/dimosserifou\/"]},{"@type":"Person","@id":"https:\/\/serifos.gr\/fr\/author\/nslivanios\/#author","url":"https:\/\/serifos.gr\/fr\/author\/nslivanios\/","name":"Stelios Livanios","image":{"@type":"ImageObject","@id":"https:\/\/serifos.gr\/fr\/%cf%80%cf%81%ce%bf%cf%83%ce%ba%ce%bb%ce%b7%cf%83%ce%b7-3%ce%bf%cf%85-%ce%b4%ce%b7%ce%bc%ce%bf%cf%84%ce%b9%ce%ba%ce%bf%cf%85-%cf%83%cf%85%ce%bc%ce%b2%ce%bf%cf%85%ce%bb%ce%b9%ce%bf%cf%85\/#authorImage","url":"https:\/\/secure.gravatar.com\/avatar\/792605e3bbc86e998535857713ea857f9fd2f4916d59659513056a03e5d789f7?s=96&d=mm&r=g","width":96,"height":96,"caption":"Stelios Livanios"}},{"@type":"WebPage","@id":"https:\/\/serifos.gr\/fr\/%cf%80%cf%81%ce%bf%cf%83%ce%ba%ce%bb%ce%b7%cf%83%ce%b7-3%ce%bf%cf%85-%ce%b4%ce%b7%ce%bc%ce%bf%cf%84%ce%b9%ce%ba%ce%bf%cf%85-%cf%83%cf%85%ce%bc%ce%b2%ce%bf%cf%85%ce%bb%ce%b9%ce%bf%cf%85\/#webpage","url":"https:\/\/serifos.gr\/fr\/%cf%80%cf%81%ce%bf%cf%83%ce%ba%ce%bb%ce%b7%cf%83%ce%b7-3%ce%bf%cf%85-%ce%b4%ce%b7%ce%bc%ce%bf%cf%84%ce%b9%ce%ba%ce%bf%cf%85-%cf%83%cf%85%ce%bc%ce%b2%ce%bf%cf%85%ce%bb%ce%b9%ce%bf%cf%85\/","name":"\u03a0\u03a1\u039f\u03a3\u039a\u039b\u0397\u03a3\u0397 3\u03bf\u03c5 \u0394\u0397\u039c\u039f\u03a4\u0399\u039a\u039f\u03a5 \u03a3\u03a5\u039c\u0392\u039f\u03a5\u039b\u0399\u039f\u03a5 - Serifos.gr","description":"\u03a0\u03a1\u039f\u03a3\u039a\u039b\u0397\u03a3\u0397-3\u03bf\u03c5-\u0394\u03a3","inLanguage":"fr-FR","isPartOf":{"@id":"https:\/\/serifos.gr\/fr\/#website"},"breadcrumb":{"@id":"https:\/\/serifos.gr\/fr\/%cf%80%cf%81%ce%bf%cf%83%ce%ba%ce%bb%ce%b7%cf%83%ce%b7-3%ce%bf%cf%85-%ce%b4%ce%b7%ce%bc%ce%bf%cf%84%ce%b9%ce%ba%ce%bf%cf%85-%cf%83%cf%85%ce%bc%ce%b2%ce%bf%cf%85%ce%bb%ce%b9%ce%bf%cf%85\/#breadcrumblist"},"author":{"@id":"https:\/\/serifos.gr\/fr\/author\/nslivanios\/#author"},"creator":{"@id":"https:\/\/serifos.gr\/fr\/author\/nslivanios\/#author"},"datePublished":"2021-01-21T18:04:00+03:00","dateModified":"2021-01-26T18:06:00+03:00"},{"@type":"WebSite","@id":"https:\/\/serifos.gr\/fr\/#website","url":"https:\/\/serifos.gr\/fr\/","name":"Serifos.gr","description":"\u0399\u03c3\u03c4\u03bf\u03c3\u03b5\u03bb\u03af\u03b4\u03b1 \u0394\u03ae\u03bc\u03bf\u03c5 \u03a3\u03b5\u03c1\u03af\u03c6\u03bf\u03c5","inLanguage":"fr-FR","publisher":{"@id":"https:\/\/serifos.gr\/fr\/#organization"}}]},"og:locale":"fr_FR","og:site_name":"Serifos.gr - \u0399\u03c3\u03c4\u03bf\u03c3\u03b5\u03bb\u03af\u03b4\u03b1 \u0394\u03ae\u03bc\u03bf\u03c5 \u03a3\u03b5\u03c1\u03af\u03c6\u03bf\u03c5","og:type":"article","og:title":"\u03a0\u03a1\u039f\u03a3\u039a\u039b\u0397\u03a3\u0397 3\u03bf\u03c5 \u0394\u0397\u039c\u039f\u03a4\u0399\u039a\u039f\u03a5 \u03a3\u03a5\u039c\u0392\u039f\u03a5\u039b\u0399\u039f\u03a5 - Serifos.gr","og:description":"\u03a0\u03a1\u039f\u03a3\u039a\u039b\u0397\u03a3\u0397-3\u03bf\u03c5-\u0394\u03a3","og:url":"https:\/\/serifos.gr\/fr\/%cf%80%cf%81%ce%bf%cf%83%ce%ba%ce%bb%ce%b7%cf%83%ce%b7-3%ce%bf%cf%85-%ce%b4%ce%b7%ce%bc%ce%bf%cf%84%ce%b9%ce%ba%ce%bf%cf%85-%cf%83%cf%85%ce%bc%ce%b2%ce%bf%cf%85%ce%bb%ce%b9%ce%bf%cf%85\/","og:image":"https:\/\/serifos.gr\/wp-content\/uploads\/2017\/08\/Logo_final.png","og:image:secure_url":"https:\/\/serifos.gr\/wp-content\/uploads\/2017\/08\/Logo_final.png","og:image:width":181,"og:image:height":46,"article:published_time":"2021-01-21T15:04:00+00:00","article:modified_time":"2021-01-26T15:06:00+00:00","article:publisher":"https:\/\/www.facebook.com\/dimosserifou\/","twitter:card":"summary","twitter:title":"\u03a0\u03a1\u039f\u03a3\u039a\u039b\u0397\u03a3\u0397 3\u03bf\u03c5 \u0394\u0397\u039c\u039f\u03a4\u0399\u039a\u039f\u03a5 \u03a3\u03a5\u039c\u0392\u039f\u03a5\u039b\u0399\u039f\u03a5 - Serifos.gr","twitter:description":"\u03a0\u03a1\u039f\u03a3\u039a\u039b\u0397\u03a3\u0397-3\u03bf\u03c5-\u0394\u03a3","twitter:image":"https:\/\/serifos.gr\/wp-content\/uploads\/2017\/08\/Logo_final.png"},"aioseo_meta_data":{"post_id":"4169","title":"#post_title #separator_sa #site_title","description":"#post_content","keywords":[],"keyphrases":{"focus":[],"additional":[]},"primary_term":null,"canonical_url":null,"og_title":null,"og_description":null,"og_object_type":"default","og_image_type":"default","og_image_url":null,"og_image_width":null,"og_image_height":null,"og_image_custom_url":null,"og_image_custom_fields":null,"og_video":"","og_custom_url":null,"og_article_section":null,"og_article_tags":[],"twitter_use_og":false,"twitter_card":"default","twitter_image_type":"default","twitter_image_url":null,"twitter_image_custom_url":null,"twitter_image_custom_fields":null,"twitter_title":null,"twitter_description":null,"schema":{"blockGraphs":[],"customGraphs":[],"default":{"data":{"Article":[],"Course":[],"Dataset":[],"FAQPage":[],"Movie":[],"Person":[],"Product":[],"ProductReview":[],"Car":[],"Recipe":[],"Service":[],"SoftwareApplication":[],"WebPage":[]},"graphName":"BlogPosting","isEnabled":true},"graphs":[]},"schema_type":"none","schema_type_options":"{\"webPage\":{\"webPageType\":\"WebPage\"},\"article\":{\"articleType\":\"BlogPosting\"},\"book\":[],\"course\":[],\"event\":[],\"jobPosting\":[],\"music\":[],\"person\":[],\"product\":[],\"recipe\":[],\"restaurant\":[],\"service\":[],\"software\":[],\"video\":[]}","pillar_content":false,"robots_default":true,"robots_noindex":false,"robots_noarchive":false,"robots_nosnippet":false,"robots_nofollow":false,"robots_noimageindex":false,"robots_noodp":false,"robots_notranslate":false,"robots_max_snippet":"-1","robots_max_videopreview":"-1","robots_max_imagepreview":"large","priority":null,"frequency":"default","local_seo":{"businessInfo":{"name":"","urls":{"website":"","aboutPage":"","contactPage":""},"address":{"line1":"","line2":"","zip":"","city":"","state":"","country":""},"contact":{"email":"","phone":"","fax":""},"ids":{"vatID":"","taxID":"","chamberID":""},"payment":{"priceIndication":"","currenciesAccepted":"","methodsAccepted":""},"areaServed":""},"openingHours":{"show":false,"closedLabel":"","open24h":false,"open24hLabel":"","open247":false,"use24hFormat":false,"twoSets":false,"timezone":"","hours":[]}},"breadcrumb_settings":null,"limit_modified_date":false,"ai":null,"created":"2021-01-26 15:05:58","updated":"2026-03-12 04:18:56","focus_keyword":null,"additional_keywords":null,"truseo_locale":null,"seo_analyzer_scan_date":null},"_links":{"self":[{"href":"https:\/\/serifos.gr\/fr\/wp-json\/wp\/v2\/posts\/4169","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/serifos.gr\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/serifos.gr\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/serifos.gr\/fr\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/serifos.gr\/fr\/wp-json\/wp\/v2\/comments?post=4169"}],"version-history":[{"count":0,"href":"https:\/\/serifos.gr\/fr\/wp-json\/wp\/v2\/posts\/4169\/revisions"}],"wp:attachment":[{"href":"https:\/\/serifos.gr\/fr\/wp-json\/wp\/v2\/media?parent=4169"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/serifos.gr\/fr\/wp-json\/wp\/v2\/categories?post=4169"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/serifos.gr\/fr\/wp-json\/wp\/v2\/tags?post=4169"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}