{"id":9776,"date":"2025-11-19T14:44:49","date_gmt":"2025-11-19T11:44:49","guid":{"rendered":"https:\/\/serifos.gr\/?p=9776"},"modified":"2025-11-19T14:44:51","modified_gmt":"2025-11-19T11:44:51","slug":"%ce%b1%ce%bd%ce%b1%ce%ba%ce%bf%ce%b9%ce%bd%cf%89%cf%83%ce%b7-%ce%b5%ce%bd%ce%b7%ce%bc%ce%b5%cf%81%cf%89%cf%83%ce%b7","status":"publish","type":"post","link":"https:\/\/serifos.gr\/en\/%ce%b1%ce%bd%ce%b1%ce%ba%ce%bf%ce%b9%ce%bd%cf%89%cf%83%ce%b7-%ce%b5%ce%bd%ce%b7%ce%bc%ce%b5%cf%81%cf%89%cf%83%ce%b7\/","title":{"rendered":"\u0391\u039d\u0391\u039a\u039f\u0399\u039d\u03a9\u03a3\u0397- \u0395\u039d\u0397\u039c\u0395\u03a1\u03a9\u03a3\u0397"},"content":{"rendered":"<div class=\"wp-block-pdfemb-pdf-embedder-viewer\"><a href=\"https:\/\/serifos.gr\/wp-content\/uploads\/2025\/11\/20251119130150253.pdf\" class=\"pdfemb-viewer\" style=\"\" data-width=\"max\" data-height=\"max\" data-toolbar=\"bottom\" data-toolbar-fixed=\"off\">20251119130150253<\/a><\/div>\n<p class=\"wp-block-pdfemb-pdf-embedder-viewer\"><\/p>","protected":false},"excerpt":{"rendered":"","protected":false},"author":2,"featured_media":0,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_monsterinsights_skip_tracking":false,"footnotes":"","_links_to":"","_links_to_target":""},"categories":[86],"tags":[],"class_list":["post-9776","post","type-post","status-publish","format-standard","hentry","category-86"],"aioseo_notices":[],"aioseo_head":"\n\t\t<!-- All in One SEO 5.0.0.1 - aioseo.com -->\n\t<meta name=\"description\" content=\"20251119130150253\" \/>\n\t<meta name=\"robots\" content=\"max-image-preview:large\" \/>\n\t<meta name=\"author\" content=\"Stelios Livanios\"\/>\n\t<link rel=\"canonical\" href=\"https:\/\/serifos.gr\/en\/%ce%b1%ce%bd%ce%b1%ce%ba%ce%bf%ce%b9%ce%bd%cf%89%cf%83%ce%b7-%ce%b5%ce%bd%ce%b7%ce%bc%ce%b5%cf%81%cf%89%cf%83%ce%b7\/\" \/>\n\t<meta name=\"generator\" content=\"All in One SEO (AIOSEO) 5.0.0.1\" \/>\n\t\t<meta property=\"og:locale\" content=\"en_GB\" \/>\n\t\t<meta property=\"og:site_name\" content=\"Serifos.gr - \u0399\u03c3\u03c4\u03bf\u03c3\u03b5\u03bb\u03af\u03b4\u03b1 \u0394\u03ae\u03bc\u03bf\u03c5 \u03a3\u03b5\u03c1\u03af\u03c6\u03bf\u03c5\" \/>\n\t\t<meta property=\"og:type\" content=\"article\" \/>\n\t\t<meta property=\"og:title\" content=\"\u0391\u039d\u0391\u039a\u039f\u0399\u039d\u03a9\u03a3\u0397- \u0395\u039d\u0397\u039c\u0395\u03a1\u03a9\u03a3\u0397 - Serifos.gr\" \/>\n\t\t<meta property=\"og:description\" content=\"20251119130150253\" \/>\n\t\t<meta property=\"og:url\" content=\"https:\/\/serifos.gr\/en\/%ce%b1%ce%bd%ce%b1%ce%ba%ce%bf%ce%b9%ce%bd%cf%89%cf%83%ce%b7-%ce%b5%ce%bd%ce%b7%ce%bc%ce%b5%cf%81%cf%89%cf%83%ce%b7\/\" \/>\n\t\t<meta property=\"og:image\" content=\"https:\/\/serifos.gr\/wp-content\/uploads\/2017\/08\/Logo_final.png\" \/>\n\t\t<meta property=\"og:image:secure_url\" content=\"https:\/\/serifos.gr\/wp-content\/uploads\/2017\/08\/Logo_final.png\" \/>\n\t\t<meta property=\"og:image:width\" content=\"181\" \/>\n\t\t<meta property=\"og:image:height\" content=\"46\" \/>\n\t\t<meta property=\"article:published_time\" content=\"2025-11-19T11:44:49+00:00\" \/>\n\t\t<meta property=\"article:modified_time\" content=\"2025-11-19T11:44:51+00:00\" \/>\n\t\t<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/dimosserifou\/\" \/>\n\t\t<meta name=\"twitter:card\" content=\"summary\" \/>\n\t\t<meta name=\"twitter:title\" content=\"\u0391\u039d\u0391\u039a\u039f\u0399\u039d\u03a9\u03a3\u0397- \u0395\u039d\u0397\u039c\u0395\u03a1\u03a9\u03a3\u0397 - Serifos.gr\" \/>\n\t\t<meta name=\"twitter:description\" content=\"20251119130150253\" \/>\n\t\t<meta name=\"twitter:image\" content=\"https:\/\/serifos.gr\/wp-content\/uploads\/2017\/08\/Logo_final.png\" \/>\n\t\t<script type=\"application\/ld+json\" class=\"aioseo-schema\">\n\t\t\t{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"BlogPosting\",\"@id\":\"https:\\\/\\\/serifos.gr\\\/en\\\/%ce%b1%ce%bd%ce%b1%ce%ba%ce%bf%ce%b9%ce%bd%cf%89%cf%83%ce%b7-%ce%b5%ce%bd%ce%b7%ce%bc%ce%b5%cf%81%cf%89%cf%83%ce%b7\\\/#blogposting\",\"name\":\"\\u0391\\u039d\\u0391\\u039a\\u039f\\u0399\\u039d\\u03a9\\u03a3\\u0397- \\u0395\\u039d\\u0397\\u039c\\u0395\\u03a1\\u03a9\\u03a3\\u0397 - Serifos.gr\",\"headline\":\"\\u0391\\u039d\\u0391\\u039a\\u039f\\u0399\\u039d\\u03a9\\u03a3\\u0397- \\u0395\\u039d\\u0397\\u039c\\u0395\\u03a1\\u03a9\\u03a3\\u0397\",\"author\":{\"@id\":\"https:\\\/\\\/serifos.gr\\\/en\\\/author\\\/nslivanios\\\/#author\"},\"publisher\":{\"@id\":\"https:\\\/\\\/serifos.gr\\\/en\\\/#organization\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/serifos.gr\\\/wp-content\\\/uploads\\\/2017\\\/08\\\/Logo_final.png\",\"@id\":\"https:\\\/\\\/serifos.gr\\\/en\\\/#articleImage\",\"width\":181,\"height\":46},\"datePublished\":\"2025-11-19T14:44:49+03:00\",\"dateModified\":\"2025-11-19T14:44:51+03:00\",\"inLanguage\":\"en-GB\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/serifos.gr\\\/en\\\/%ce%b1%ce%bd%ce%b1%ce%ba%ce%bf%ce%b9%ce%bd%cf%89%cf%83%ce%b7-%ce%b5%ce%bd%ce%b7%ce%bc%ce%b5%cf%81%cf%89%cf%83%ce%b7\\\/#webpage\"},\"isPartOf\":{\"@id\":\"https:\\\/\\\/serifos.gr\\\/en\\\/%ce%b1%ce%bd%ce%b1%ce%ba%ce%bf%ce%b9%ce%bd%cf%89%cf%83%ce%b7-%ce%b5%ce%bd%ce%b7%ce%bc%ce%b5%cf%81%cf%89%cf%83%ce%b7\\\/#webpage\"},\"articleSection\":\"\\u0391\\u03bd\\u03b1\\u03ba\\u03bf\\u03b9\\u03bd\\u03ce\\u03c3\\u03b5\\u03b9\\u03c2\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/serifos.gr\\\/en\\\/%ce%b1%ce%bd%ce%b1%ce%ba%ce%bf%ce%b9%ce%bd%cf%89%cf%83%ce%b7-%ce%b5%ce%bd%ce%b7%ce%bc%ce%b5%cf%81%cf%89%cf%83%ce%b7\\\/#breadcrumblist\",\"itemListElement\":[{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/serifos.gr\\\/en#listItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/serifos.gr\\\/en\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/serifos.gr\\\/en\\\/category\\\/%ce%b1%ce%bd%ce%b1%ce%ba%ce%bf%ce%b9%ce%bd%cf%8e%cf%83%ce%b5%ce%b9%cf%82\\\/#listItem\",\"name\":\"\\u0391\\u03bd\\u03b1\\u03ba\\u03bf\\u03b9\\u03bd\\u03ce\\u03c3\\u03b5\\u03b9\\u03c2\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/serifos.gr\\\/en\\\/category\\\/%ce%b1%ce%bd%ce%b1%ce%ba%ce%bf%ce%b9%ce%bd%cf%8e%cf%83%ce%b5%ce%b9%cf%82\\\/#listItem\",\"position\":2,\"name\":\"\\u0391\\u03bd\\u03b1\\u03ba\\u03bf\\u03b9\\u03bd\\u03ce\\u03c3\\u03b5\\u03b9\\u03c2\",\"item\":\"https:\\\/\\\/serifos.gr\\\/en\\\/category\\\/%ce%b1%ce%bd%ce%b1%ce%ba%ce%bf%ce%b9%ce%bd%cf%8e%cf%83%ce%b5%ce%b9%cf%82\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/serifos.gr\\\/en\\\/%ce%b1%ce%bd%ce%b1%ce%ba%ce%bf%ce%b9%ce%bd%cf%89%cf%83%ce%b7-%ce%b5%ce%bd%ce%b7%ce%bc%ce%b5%cf%81%cf%89%cf%83%ce%b7\\\/#listItem\",\"name\":\"\\u0391\\u039d\\u0391\\u039a\\u039f\\u0399\\u039d\\u03a9\\u03a3\\u0397- \\u0395\\u039d\\u0397\\u039c\\u0395\\u03a1\\u03a9\\u03a3\\u0397\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/serifos.gr\\\/en#listItem\",\"name\":\"Home\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/serifos.gr\\\/en\\\/%ce%b1%ce%bd%ce%b1%ce%ba%ce%bf%ce%b9%ce%bd%cf%89%cf%83%ce%b7-%ce%b5%ce%bd%ce%b7%ce%bc%ce%b5%cf%81%cf%89%cf%83%ce%b7\\\/#listItem\",\"position\":3,\"name\":\"\\u0391\\u039d\\u0391\\u039a\\u039f\\u0399\\u039d\\u03a9\\u03a3\\u0397- \\u0395\\u039d\\u0397\\u039c\\u0395\\u03a1\\u03a9\\u03a3\\u0397\",\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/serifos.gr\\\/en\\\/category\\\/%ce%b1%ce%bd%ce%b1%ce%ba%ce%bf%ce%b9%ce%bd%cf%8e%cf%83%ce%b5%ce%b9%cf%82\\\/#listItem\",\"name\":\"\\u0391\\u03bd\\u03b1\\u03ba\\u03bf\\u03b9\\u03bd\\u03ce\\u03c3\\u03b5\\u03b9\\u03c2\"}}]},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/serifos.gr\\\/en\\\/#organization\",\"name\":\"Serifos.gr\",\"description\":\"\\u0399\\u03c3\\u03c4\\u03bf\\u03c3\\u03b5\\u03bb\\u03af\\u03b4\\u03b1 \\u0394\\u03ae\\u03bc\\u03bf\\u03c5 \\u03a3\\u03b5\\u03c1\\u03af\\u03c6\\u03bf\\u03c5\",\"url\":\"https:\\\/\\\/serifos.gr\\\/en\\\/\",\"telephone\":\"+302281051210\",\"logo\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/serifos.gr\\\/wp-content\\\/uploads\\\/2017\\\/08\\\/Logo_final.png\",\"@id\":\"https:\\\/\\\/serifos.gr\\\/en\\\/%ce%b1%ce%bd%ce%b1%ce%ba%ce%bf%ce%b9%ce%bd%cf%89%cf%83%ce%b7-%ce%b5%ce%bd%ce%b7%ce%bc%ce%b5%cf%81%cf%89%cf%83%ce%b7\\\/#organizationLogo\",\"width\":181,\"height\":46},\"image\":{\"@id\":\"https:\\\/\\\/serifos.gr\\\/en\\\/%ce%b1%ce%bd%ce%b1%ce%ba%ce%bf%ce%b9%ce%bd%cf%89%cf%83%ce%b7-%ce%b5%ce%bd%ce%b7%ce%bc%ce%b5%cf%81%cf%89%cf%83%ce%b7\\\/#organizationLogo\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/dimosserifou\\\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/serifos.gr\\\/en\\\/author\\\/nslivanios\\\/#author\",\"url\":\"https:\\\/\\\/serifos.gr\\\/en\\\/author\\\/nslivanios\\\/\",\"name\":\"Stelios Livanios\",\"image\":{\"@type\":\"ImageObject\",\"@id\":\"https:\\\/\\\/serifos.gr\\\/en\\\/%ce%b1%ce%bd%ce%b1%ce%ba%ce%bf%ce%b9%ce%bd%cf%89%cf%83%ce%b7-%ce%b5%ce%bd%ce%b7%ce%bc%ce%b5%cf%81%cf%89%cf%83%ce%b7\\\/#authorImage\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/792605e3bbc86e998535857713ea857f9fd2f4916d59659513056a03e5d789f7?s=96&d=mm&r=g\",\"width\":96,\"height\":96,\"caption\":\"Stelios Livanios\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/serifos.gr\\\/en\\\/%ce%b1%ce%bd%ce%b1%ce%ba%ce%bf%ce%b9%ce%bd%cf%89%cf%83%ce%b7-%ce%b5%ce%bd%ce%b7%ce%bc%ce%b5%cf%81%cf%89%cf%83%ce%b7\\\/#webpage\",\"url\":\"https:\\\/\\\/serifos.gr\\\/en\\\/%ce%b1%ce%bd%ce%b1%ce%ba%ce%bf%ce%b9%ce%bd%cf%89%cf%83%ce%b7-%ce%b5%ce%bd%ce%b7%ce%bc%ce%b5%cf%81%cf%89%cf%83%ce%b7\\\/\",\"name\":\"\\u0391\\u039d\\u0391\\u039a\\u039f\\u0399\\u039d\\u03a9\\u03a3\\u0397- \\u0395\\u039d\\u0397\\u039c\\u0395\\u03a1\\u03a9\\u03a3\\u0397 - Serifos.gr\",\"description\":\"20251119130150253\",\"inLanguage\":\"en-GB\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/serifos.gr\\\/en\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/serifos.gr\\\/en\\\/%ce%b1%ce%bd%ce%b1%ce%ba%ce%bf%ce%b9%ce%bd%cf%89%cf%83%ce%b7-%ce%b5%ce%bd%ce%b7%ce%bc%ce%b5%cf%81%cf%89%cf%83%ce%b7\\\/#breadcrumblist\"},\"author\":{\"@id\":\"https:\\\/\\\/serifos.gr\\\/en\\\/author\\\/nslivanios\\\/#author\"},\"creator\":{\"@id\":\"https:\\\/\\\/serifos.gr\\\/en\\\/author\\\/nslivanios\\\/#author\"},\"datePublished\":\"2025-11-19T14:44:49+03:00\",\"dateModified\":\"2025-11-19T14:44:51+03:00\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/serifos.gr\\\/en\\\/#website\",\"url\":\"https:\\\/\\\/serifos.gr\\\/en\\\/\",\"name\":\"Serifos.gr\",\"description\":\"\\u0399\\u03c3\\u03c4\\u03bf\\u03c3\\u03b5\\u03bb\\u03af\\u03b4\\u03b1 \\u0394\\u03ae\\u03bc\\u03bf\\u03c5 \\u03a3\\u03b5\\u03c1\\u03af\\u03c6\\u03bf\\u03c5\",\"inLanguage\":\"en-GB\",\"publisher\":{\"@id\":\"https:\\\/\\\/serifos.gr\\\/en\\\/#organization\"}}]}\n\t\t<\/script>\n\t\t<!-- All in One SEO -->\n\n","aioseo_head_json":{"title":"\u0391\u039d\u0391\u039a\u039f\u0399\u039d\u03a9\u03a3\u0397- \u0395\u039d\u0397\u039c\u0395\u03a1\u03a9\u03a3\u0397 - Serifos.gr","description":"20251119130150253","canonical_url":"https:\/\/serifos.gr\/en\/%ce%b1%ce%bd%ce%b1%ce%ba%ce%bf%ce%b9%ce%bd%cf%89%cf%83%ce%b7-%ce%b5%ce%bd%ce%b7%ce%bc%ce%b5%cf%81%cf%89%cf%83%ce%b7\/","robots":"max-image-preview:large","keywords":"","webmasterTools":{"miscellaneous":""},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"BlogPosting","@id":"https:\/\/serifos.gr\/en\/%ce%b1%ce%bd%ce%b1%ce%ba%ce%bf%ce%b9%ce%bd%cf%89%cf%83%ce%b7-%ce%b5%ce%bd%ce%b7%ce%bc%ce%b5%cf%81%cf%89%cf%83%ce%b7\/#blogposting","name":"\u0391\u039d\u0391\u039a\u039f\u0399\u039d\u03a9\u03a3\u0397- \u0395\u039d\u0397\u039c\u0395\u03a1\u03a9\u03a3\u0397 - Serifos.gr","headline":"\u0391\u039d\u0391\u039a\u039f\u0399\u039d\u03a9\u03a3\u0397- \u0395\u039d\u0397\u039c\u0395\u03a1\u03a9\u03a3\u0397","author":{"@id":"https:\/\/serifos.gr\/en\/author\/nslivanios\/#author"},"publisher":{"@id":"https:\/\/serifos.gr\/en\/#organization"},"image":{"@type":"ImageObject","url":"https:\/\/serifos.gr\/wp-content\/uploads\/2017\/08\/Logo_final.png","@id":"https:\/\/serifos.gr\/en\/#articleImage","width":181,"height":46},"datePublished":"2025-11-19T14:44:49+03:00","dateModified":"2025-11-19T14:44:51+03:00","inLanguage":"en-GB","mainEntityOfPage":{"@id":"https:\/\/serifos.gr\/en\/%ce%b1%ce%bd%ce%b1%ce%ba%ce%bf%ce%b9%ce%bd%cf%89%cf%83%ce%b7-%ce%b5%ce%bd%ce%b7%ce%bc%ce%b5%cf%81%cf%89%cf%83%ce%b7\/#webpage"},"isPartOf":{"@id":"https:\/\/serifos.gr\/en\/%ce%b1%ce%bd%ce%b1%ce%ba%ce%bf%ce%b9%ce%bd%cf%89%cf%83%ce%b7-%ce%b5%ce%bd%ce%b7%ce%bc%ce%b5%cf%81%cf%89%cf%83%ce%b7\/#webpage"},"articleSection":"\u0391\u03bd\u03b1\u03ba\u03bf\u03b9\u03bd\u03ce\u03c3\u03b5\u03b9\u03c2"},{"@type":"BreadcrumbList","@id":"https:\/\/serifos.gr\/en\/%ce%b1%ce%bd%ce%b1%ce%ba%ce%bf%ce%b9%ce%bd%cf%89%cf%83%ce%b7-%ce%b5%ce%bd%ce%b7%ce%bc%ce%b5%cf%81%cf%89%cf%83%ce%b7\/#breadcrumblist","itemListElement":[{"@type":"ListItem","@id":"https:\/\/serifos.gr\/en#listItem","position":1,"name":"Home","item":"https:\/\/serifos.gr\/en","nextItem":{"@type":"ListItem","@id":"https:\/\/serifos.gr\/en\/category\/%ce%b1%ce%bd%ce%b1%ce%ba%ce%bf%ce%b9%ce%bd%cf%8e%cf%83%ce%b5%ce%b9%cf%82\/#listItem","name":"\u0391\u03bd\u03b1\u03ba\u03bf\u03b9\u03bd\u03ce\u03c3\u03b5\u03b9\u03c2"}},{"@type":"ListItem","@id":"https:\/\/serifos.gr\/en\/category\/%ce%b1%ce%bd%ce%b1%ce%ba%ce%bf%ce%b9%ce%bd%cf%8e%cf%83%ce%b5%ce%b9%cf%82\/#listItem","position":2,"name":"\u0391\u03bd\u03b1\u03ba\u03bf\u03b9\u03bd\u03ce\u03c3\u03b5\u03b9\u03c2","item":"https:\/\/serifos.gr\/en\/category\/%ce%b1%ce%bd%ce%b1%ce%ba%ce%bf%ce%b9%ce%bd%cf%8e%cf%83%ce%b5%ce%b9%cf%82\/","nextItem":{"@type":"ListItem","@id":"https:\/\/serifos.gr\/en\/%ce%b1%ce%bd%ce%b1%ce%ba%ce%bf%ce%b9%ce%bd%cf%89%cf%83%ce%b7-%ce%b5%ce%bd%ce%b7%ce%bc%ce%b5%cf%81%cf%89%cf%83%ce%b7\/#listItem","name":"\u0391\u039d\u0391\u039a\u039f\u0399\u039d\u03a9\u03a3\u0397- \u0395\u039d\u0397\u039c\u0395\u03a1\u03a9\u03a3\u0397"},"previousItem":{"@type":"ListItem","@id":"https:\/\/serifos.gr\/en#listItem","name":"Home"}},{"@type":"ListItem","@id":"https:\/\/serifos.gr\/en\/%ce%b1%ce%bd%ce%b1%ce%ba%ce%bf%ce%b9%ce%bd%cf%89%cf%83%ce%b7-%ce%b5%ce%bd%ce%b7%ce%bc%ce%b5%cf%81%cf%89%cf%83%ce%b7\/#listItem","position":3,"name":"\u0391\u039d\u0391\u039a\u039f\u0399\u039d\u03a9\u03a3\u0397- \u0395\u039d\u0397\u039c\u0395\u03a1\u03a9\u03a3\u0397","previousItem":{"@type":"ListItem","@id":"https:\/\/serifos.gr\/en\/category\/%ce%b1%ce%bd%ce%b1%ce%ba%ce%bf%ce%b9%ce%bd%cf%8e%cf%83%ce%b5%ce%b9%cf%82\/#listItem","name":"\u0391\u03bd\u03b1\u03ba\u03bf\u03b9\u03bd\u03ce\u03c3\u03b5\u03b9\u03c2"}}]},{"@type":"Organization","@id":"https:\/\/serifos.gr\/en\/#organization","name":"Serifos.gr","description":"\u0399\u03c3\u03c4\u03bf\u03c3\u03b5\u03bb\u03af\u03b4\u03b1 \u0394\u03ae\u03bc\u03bf\u03c5 \u03a3\u03b5\u03c1\u03af\u03c6\u03bf\u03c5","url":"https:\/\/serifos.gr\/en\/","telephone":"+302281051210","logo":{"@type":"ImageObject","url":"https:\/\/serifos.gr\/wp-content\/uploads\/2017\/08\/Logo_final.png","@id":"https:\/\/serifos.gr\/en\/%ce%b1%ce%bd%ce%b1%ce%ba%ce%bf%ce%b9%ce%bd%cf%89%cf%83%ce%b7-%ce%b5%ce%bd%ce%b7%ce%bc%ce%b5%cf%81%cf%89%cf%83%ce%b7\/#organizationLogo","width":181,"height":46},"image":{"@id":"https:\/\/serifos.gr\/en\/%ce%b1%ce%bd%ce%b1%ce%ba%ce%bf%ce%b9%ce%bd%cf%89%cf%83%ce%b7-%ce%b5%ce%bd%ce%b7%ce%bc%ce%b5%cf%81%cf%89%cf%83%ce%b7\/#organizationLogo"},"sameAs":["https:\/\/www.facebook.com\/dimosserifou\/"]},{"@type":"Person","@id":"https:\/\/serifos.gr\/en\/author\/nslivanios\/#author","url":"https:\/\/serifos.gr\/en\/author\/nslivanios\/","name":"Stelios Livanios","image":{"@type":"ImageObject","@id":"https:\/\/serifos.gr\/en\/%ce%b1%ce%bd%ce%b1%ce%ba%ce%bf%ce%b9%ce%bd%cf%89%cf%83%ce%b7-%ce%b5%ce%bd%ce%b7%ce%bc%ce%b5%cf%81%cf%89%cf%83%ce%b7\/#authorImage","url":"https:\/\/secure.gravatar.com\/avatar\/792605e3bbc86e998535857713ea857f9fd2f4916d59659513056a03e5d789f7?s=96&d=mm&r=g","width":96,"height":96,"caption":"Stelios Livanios"}},{"@type":"WebPage","@id":"https:\/\/serifos.gr\/en\/%ce%b1%ce%bd%ce%b1%ce%ba%ce%bf%ce%b9%ce%bd%cf%89%cf%83%ce%b7-%ce%b5%ce%bd%ce%b7%ce%bc%ce%b5%cf%81%cf%89%cf%83%ce%b7\/#webpage","url":"https:\/\/serifos.gr\/en\/%ce%b1%ce%bd%ce%b1%ce%ba%ce%bf%ce%b9%ce%bd%cf%89%cf%83%ce%b7-%ce%b5%ce%bd%ce%b7%ce%bc%ce%b5%cf%81%cf%89%cf%83%ce%b7\/","name":"\u0391\u039d\u0391\u039a\u039f\u0399\u039d\u03a9\u03a3\u0397- \u0395\u039d\u0397\u039c\u0395\u03a1\u03a9\u03a3\u0397 - Serifos.gr","description":"20251119130150253","inLanguage":"en-GB","isPartOf":{"@id":"https:\/\/serifos.gr\/en\/#website"},"breadcrumb":{"@id":"https:\/\/serifos.gr\/en\/%ce%b1%ce%bd%ce%b1%ce%ba%ce%bf%ce%b9%ce%bd%cf%89%cf%83%ce%b7-%ce%b5%ce%bd%ce%b7%ce%bc%ce%b5%cf%81%cf%89%cf%83%ce%b7\/#breadcrumblist"},"author":{"@id":"https:\/\/serifos.gr\/en\/author\/nslivanios\/#author"},"creator":{"@id":"https:\/\/serifos.gr\/en\/author\/nslivanios\/#author"},"datePublished":"2025-11-19T14:44:49+03:00","dateModified":"2025-11-19T14:44:51+03:00"},{"@type":"WebSite","@id":"https:\/\/serifos.gr\/en\/#website","url":"https:\/\/serifos.gr\/en\/","name":"Serifos.gr","description":"\u0399\u03c3\u03c4\u03bf\u03c3\u03b5\u03bb\u03af\u03b4\u03b1 \u0394\u03ae\u03bc\u03bf\u03c5 \u03a3\u03b5\u03c1\u03af\u03c6\u03bf\u03c5","inLanguage":"en-GB","publisher":{"@id":"https:\/\/serifos.gr\/en\/#organization"}}]},"og:locale":"en_GB","og:site_name":"Serifos.gr - \u0399\u03c3\u03c4\u03bf\u03c3\u03b5\u03bb\u03af\u03b4\u03b1 \u0394\u03ae\u03bc\u03bf\u03c5 \u03a3\u03b5\u03c1\u03af\u03c6\u03bf\u03c5","og:type":"article","og:title":"\u0391\u039d\u0391\u039a\u039f\u0399\u039d\u03a9\u03a3\u0397- \u0395\u039d\u0397\u039c\u0395\u03a1\u03a9\u03a3\u0397 - Serifos.gr","og:description":"20251119130150253","og:url":"https:\/\/serifos.gr\/en\/%ce%b1%ce%bd%ce%b1%ce%ba%ce%bf%ce%b9%ce%bd%cf%89%cf%83%ce%b7-%ce%b5%ce%bd%ce%b7%ce%bc%ce%b5%cf%81%cf%89%cf%83%ce%b7\/","og:image":"https:\/\/serifos.gr\/wp-content\/uploads\/2017\/08\/Logo_final.png","og:image:secure_url":"https:\/\/serifos.gr\/wp-content\/uploads\/2017\/08\/Logo_final.png","og:image:width":181,"og:image:height":46,"article:published_time":"2025-11-19T11:44:49+00:00","article:modified_time":"2025-11-19T11:44:51+00:00","article:publisher":"https:\/\/www.facebook.com\/dimosserifou\/","twitter:card":"summary","twitter:title":"\u0391\u039d\u0391\u039a\u039f\u0399\u039d\u03a9\u03a3\u0397- \u0395\u039d\u0397\u039c\u0395\u03a1\u03a9\u03a3\u0397 - Serifos.gr","twitter:description":"20251119130150253","twitter:image":"https:\/\/serifos.gr\/wp-content\/uploads\/2017\/08\/Logo_final.png"},"aioseo_meta_data":{"post_id":"9776","title":null,"description":null,"keywords":[],"keyphrases":{"focus":{"keyphrase":"","score":0,"analysis":{"keyphraseInTitle":{"score":0,"maxScore":9,"error":1}}},"additional":[]},"primary_term":null,"canonical_url":null,"og_title":null,"og_description":null,"og_object_type":"default","og_image_type":"default","og_image_url":null,"og_image_width":null,"og_image_height":null,"og_image_custom_url":null,"og_image_custom_fields":null,"og_video":"","og_custom_url":null,"og_article_section":null,"og_article_tags":[],"twitter_use_og":false,"twitter_card":"default","twitter_image_type":"default","twitter_image_url":null,"twitter_image_custom_url":null,"twitter_image_custom_fields":null,"twitter_title":null,"twitter_description":null,"schema":{"blockGraphs":[],"customGraphs":[],"default":{"data":{"Article":[],"Course":[],"Dataset":[],"FAQPage":[],"Movie":[],"Person":[],"Product":[],"ProductReview":[],"Car":[],"Recipe":[],"Service":[],"SoftwareApplication":[],"WebPage":[]},"graphName":"BlogPosting","isEnabled":true},"graphs":[]},"schema_type":"default","schema_type_options":null,"pillar_content":false,"robots_default":true,"robots_noindex":false,"robots_noarchive":false,"robots_nosnippet":false,"robots_nofollow":false,"robots_noimageindex":false,"robots_noodp":false,"robots_notranslate":false,"robots_max_snippet":"-1","robots_max_videopreview":"-1","robots_max_imagepreview":"large","priority":null,"frequency":"default","local_seo":null,"breadcrumb_settings":null,"limit_modified_date":false,"ai":null,"created":"2025-11-19 11:44:51","updated":"2026-03-12 08:06:20","focus_keyword":null,"additional_keywords":null,"truseo_locale":null,"seo_analyzer_scan_date":null},"_links":{"self":[{"href":"https:\/\/serifos.gr\/en\/wp-json\/wp\/v2\/posts\/9776","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/serifos.gr\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/serifos.gr\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/serifos.gr\/en\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/serifos.gr\/en\/wp-json\/wp\/v2\/comments?post=9776"}],"version-history":[{"count":1,"href":"https:\/\/serifos.gr\/en\/wp-json\/wp\/v2\/posts\/9776\/revisions"}],"predecessor-version":[{"id":9778,"href":"https:\/\/serifos.gr\/en\/wp-json\/wp\/v2\/posts\/9776\/revisions\/9778"}],"wp:attachment":[{"href":"https:\/\/serifos.gr\/en\/wp-json\/wp\/v2\/media?parent=9776"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/serifos.gr\/en\/wp-json\/wp\/v2\/categories?post=9776"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/serifos.gr\/en\/wp-json\/wp\/v2\/tags?post=9776"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}