{"id":7035,"date":"2023-02-10T10:41:00","date_gmt":"2023-02-10T07:41:00","guid":{"rendered":"https:\/\/serifos.gr\/?p=7035"},"modified":"2023-05-12T10:45:18","modified_gmt":"2023-05-12T07:45:18","slug":"%cf%80%cf%81%ce%bf%cf%83%ce%ba%ce%bb%ce%b7%cf%83%ce%b7-%cf%83%cf%85%ce%bd%ce%b5%ce%b4%cf%81%ce%b9%ce%b1%cf%83%ce%b7%cf%83-2%ce%bf%cf%85-%ce%b4%ce%b7%ce%bc%ce%bf%cf%84%ce%b9%ce%ba%ce%bf%cf%85-%cf%83","status":"publish","type":"post","link":"https:\/\/serifos.gr\/en\/%cf%80%cf%81%ce%bf%cf%83%ce%ba%ce%bb%ce%b7%cf%83%ce%b7-%cf%83%cf%85%ce%bd%ce%b5%ce%b4%cf%81%ce%b9%ce%b1%cf%83%ce%b7%cf%83-2%ce%bf%cf%85-%ce%b4%ce%b7%ce%bc%ce%bf%cf%84%ce%b9%ce%ba%ce%bf%cf%85-%cf%83\/","title":{"rendered":"\u03a0\u03a1\u039f\u03a3\u039a\u039b\u0397\u03a3\u0397 \u03a3\u03a5\u039d\u0395\u0394\u03a1\u0399\u0391\u03a3\u0397\u03a3 2\u03bf\u03c5 \u0394\u0397\u039c\u039f\u03a4\u0399\u039a\u039f\u03a5 \u03a3\u03a5\u039c\u0392\u039f\u03a5\u039b\u0399\u039f\u03a5 2023."},"content":{"rendered":"<div class=\"wp-block-pdfemb-pdf-embedder-viewer\"><a href=\"https:\/\/serifos.gr\/wp-content\/uploads\/2023\/05\/\u03a0\u03a1\u039f\u03a3\u039a\u039b\u0397\u03a3\u0397-\u0394\u03a3-2-2023.pdf\" class=\"pdfemb-viewer\" style=\"\" data-width=\"max\" data-height=\"max\" data-toolbar=\"bottom\" data-toolbar-fixed=\"off\">\u03a0\u03a1\u039f\u03a3\u039a\u039b\u0397\u03a3\u0397-\u0394\u03a3-2-2023<\/a><\/div>\n<p class=\"wp-block-pdfemb-pdf-embedder-viewer\"><\/p>","protected":false},"excerpt":{"rendered":"","protected":false},"author":2,"featured_media":0,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_monsterinsights_skip_tracking":false,"footnotes":"","_links_to":"","_links_to_target":""},"categories":[79],"tags":[],"class_list":["post-7035","post","type-post","status-publish","format-standard","hentry","category-proskliseis_dimotikou_symvouliou"],"aioseo_notices":[],"aioseo_head":"\n\t\t<!-- All in One SEO 5.0.0.1 - aioseo.com -->\n\t<meta name=\"description\" content=\"\u03a0\u03a1\u039f\u03a3\u039a\u039b\u0397\u03a3\u0397-\u0394\u03a3-2-2023\" \/>\n\t<meta name=\"robots\" content=\"max-image-preview:large\" \/>\n\t<meta name=\"author\" content=\"Stelios Livanios\"\/>\n\t<link rel=\"canonical\" href=\"https:\/\/serifos.gr\/en\/%cf%80%cf%81%ce%bf%cf%83%ce%ba%ce%bb%ce%b7%cf%83%ce%b7-%cf%83%cf%85%ce%bd%ce%b5%ce%b4%cf%81%ce%b9%ce%b1%cf%83%ce%b7%cf%83-2%ce%bf%cf%85-%ce%b4%ce%b7%ce%bc%ce%bf%cf%84%ce%b9%ce%ba%ce%bf%cf%85-%cf%83\/\" \/>\n\t<meta name=\"generator\" content=\"All in One SEO (AIOSEO) 5.0.0.1\" \/>\n\t\t<meta property=\"og:locale\" content=\"en_GB\" \/>\n\t\t<meta property=\"og:site_name\" content=\"Serifos.gr - \u0399\u03c3\u03c4\u03bf\u03c3\u03b5\u03bb\u03af\u03b4\u03b1 \u0394\u03ae\u03bc\u03bf\u03c5 \u03a3\u03b5\u03c1\u03af\u03c6\u03bf\u03c5\" \/>\n\t\t<meta property=\"og:type\" content=\"article\" \/>\n\t\t<meta property=\"og:title\" content=\"\u03a0\u03a1\u039f\u03a3\u039a\u039b\u0397\u03a3\u0397 \u03a3\u03a5\u039d\u0395\u0394\u03a1\u0399\u0391\u03a3\u0397\u03a3 2\u03bf\u03c5 \u0394\u0397\u039c\u039f\u03a4\u0399\u039a\u039f\u03a5 \u03a3\u03a5\u039c\u0392\u039f\u03a5\u039b\u0399\u039f\u03a5 2023. - Serifos.gr\" \/>\n\t\t<meta property=\"og:description\" content=\"\u03a0\u03a1\u039f\u03a3\u039a\u039b\u0397\u03a3\u0397-\u0394\u03a3-2-2023\" \/>\n\t\t<meta property=\"og:url\" content=\"https:\/\/serifos.gr\/en\/%cf%80%cf%81%ce%bf%cf%83%ce%ba%ce%bb%ce%b7%cf%83%ce%b7-%cf%83%cf%85%ce%bd%ce%b5%ce%b4%cf%81%ce%b9%ce%b1%cf%83%ce%b7%cf%83-2%ce%bf%cf%85-%ce%b4%ce%b7%ce%bc%ce%bf%cf%84%ce%b9%ce%ba%ce%bf%cf%85-%cf%83\/\" \/>\n\t\t<meta property=\"og:image\" content=\"https:\/\/serifos.gr\/wp-content\/uploads\/2017\/08\/Logo_final.png\" \/>\n\t\t<meta property=\"og:image:secure_url\" content=\"https:\/\/serifos.gr\/wp-content\/uploads\/2017\/08\/Logo_final.png\" \/>\n\t\t<meta property=\"og:image:width\" content=\"181\" \/>\n\t\t<meta property=\"og:image:height\" content=\"46\" \/>\n\t\t<meta property=\"article:published_time\" content=\"2023-02-10T07:41:00+00:00\" \/>\n\t\t<meta property=\"article:modified_time\" content=\"2023-05-12T07:45:18+00:00\" \/>\n\t\t<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/dimosserifou\/\" \/>\n\t\t<meta name=\"twitter:card\" content=\"summary\" \/>\n\t\t<meta name=\"twitter:title\" content=\"\u03a0\u03a1\u039f\u03a3\u039a\u039b\u0397\u03a3\u0397 \u03a3\u03a5\u039d\u0395\u0394\u03a1\u0399\u0391\u03a3\u0397\u03a3 2\u03bf\u03c5 \u0394\u0397\u039c\u039f\u03a4\u0399\u039a\u039f\u03a5 \u03a3\u03a5\u039c\u0392\u039f\u03a5\u039b\u0399\u039f\u03a5 2023. - Serifos.gr\" \/>\n\t\t<meta name=\"twitter:description\" content=\"\u03a0\u03a1\u039f\u03a3\u039a\u039b\u0397\u03a3\u0397-\u0394\u03a3-2-2023\" \/>\n\t\t<meta name=\"twitter:image\" content=\"https:\/\/serifos.gr\/wp-content\/uploads\/2017\/08\/Logo_final.png\" \/>\n\t\t<script type=\"application\/ld+json\" class=\"aioseo-schema\">\n\t\t\t{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"BlogPosting\",\"@id\":\"https:\\\/\\\/serifos.gr\\\/en\\\/%cf%80%cf%81%ce%bf%cf%83%ce%ba%ce%bb%ce%b7%cf%83%ce%b7-%cf%83%cf%85%ce%bd%ce%b5%ce%b4%cf%81%ce%b9%ce%b1%cf%83%ce%b7%cf%83-2%ce%bf%cf%85-%ce%b4%ce%b7%ce%bc%ce%bf%cf%84%ce%b9%ce%ba%ce%bf%cf%85-%cf%83\\\/#blogposting\",\"name\":\"\\u03a0\\u03a1\\u039f\\u03a3\\u039a\\u039b\\u0397\\u03a3\\u0397 \\u03a3\\u03a5\\u039d\\u0395\\u0394\\u03a1\\u0399\\u0391\\u03a3\\u0397\\u03a3 2\\u03bf\\u03c5 \\u0394\\u0397\\u039c\\u039f\\u03a4\\u0399\\u039a\\u039f\\u03a5 \\u03a3\\u03a5\\u039c\\u0392\\u039f\\u03a5\\u039b\\u0399\\u039f\\u03a5 2023. - Serifos.gr\",\"headline\":\"\\u03a0\\u03a1\\u039f\\u03a3\\u039a\\u039b\\u0397\\u03a3\\u0397 \\u03a3\\u03a5\\u039d\\u0395\\u0394\\u03a1\\u0399\\u0391\\u03a3\\u0397\\u03a3 2\\u03bf\\u03c5 \\u0394\\u0397\\u039c\\u039f\\u03a4\\u0399\\u039a\\u039f\\u03a5 \\u03a3\\u03a5\\u039c\\u0392\\u039f\\u03a5\\u039b\\u0399\\u039f\\u03a5 2023.\",\"author\":{\"@id\":\"https:\\\/\\\/serifos.gr\\\/en\\\/author\\\/nslivanios\\\/#author\"},\"publisher\":{\"@id\":\"https:\\\/\\\/serifos.gr\\\/en\\\/#organization\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/serifos.gr\\\/wp-content\\\/uploads\\\/2017\\\/08\\\/Logo_final.png\",\"@id\":\"https:\\\/\\\/serifos.gr\\\/en\\\/#articleImage\",\"width\":181,\"height\":46},\"datePublished\":\"2023-02-10T10:41:00+03:00\",\"dateModified\":\"2023-05-12T10:45:18+03:00\",\"inLanguage\":\"en-GB\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/serifos.gr\\\/en\\\/%cf%80%cf%81%ce%bf%cf%83%ce%ba%ce%bb%ce%b7%cf%83%ce%b7-%cf%83%cf%85%ce%bd%ce%b5%ce%b4%cf%81%ce%b9%ce%b1%cf%83%ce%b7%cf%83-2%ce%bf%cf%85-%ce%b4%ce%b7%ce%bc%ce%bf%cf%84%ce%b9%ce%ba%ce%bf%cf%85-%cf%83\\\/#webpage\"},\"isPartOf\":{\"@id\":\"https:\\\/\\\/serifos.gr\\\/en\\\/%cf%80%cf%81%ce%bf%cf%83%ce%ba%ce%bb%ce%b7%cf%83%ce%b7-%cf%83%cf%85%ce%bd%ce%b5%ce%b4%cf%81%ce%b9%ce%b1%cf%83%ce%b7%cf%83-2%ce%bf%cf%85-%ce%b4%ce%b7%ce%bc%ce%bf%cf%84%ce%b9%ce%ba%ce%bf%cf%85-%cf%83\\\/#webpage\"},\"articleSection\":\"\\u03a0\\u03c1\\u03bf\\u03c3\\u03ba\\u03bb\\u03ae\\u03c3\\u03b5\\u03b9\\u03c2 \\u0394\\u03b7\\u03bc\\u03bf\\u03c4\\u03b9\\u03ba\\u03bf\\u03cd \\u03a3\\u03c5\\u03bc\\u03b2\\u03bf\\u03c5\\u03bb\\u03af\\u03bf\\u03c5\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/serifos.gr\\\/en\\\/%cf%80%cf%81%ce%bf%cf%83%ce%ba%ce%bb%ce%b7%cf%83%ce%b7-%cf%83%cf%85%ce%bd%ce%b5%ce%b4%cf%81%ce%b9%ce%b1%cf%83%ce%b7%cf%83-2%ce%bf%cf%85-%ce%b4%ce%b7%ce%bc%ce%bf%cf%84%ce%b9%ce%ba%ce%bf%cf%85-%cf%83\\\/#breadcrumblist\",\"itemListElement\":[{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/serifos.gr\\\/en#listItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/serifos.gr\\\/en\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/serifos.gr\\\/en\\\/category\\\/proskliseis_dimotikou_symvouliou\\\/#listItem\",\"name\":\"\\u03a0\\u03c1\\u03bf\\u03c3\\u03ba\\u03bb\\u03ae\\u03c3\\u03b5\\u03b9\\u03c2 \\u0394\\u03b7\\u03bc\\u03bf\\u03c4\\u03b9\\u03ba\\u03bf\\u03cd \\u03a3\\u03c5\\u03bc\\u03b2\\u03bf\\u03c5\\u03bb\\u03af\\u03bf\\u03c5\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/serifos.gr\\\/en\\\/category\\\/proskliseis_dimotikou_symvouliou\\\/#listItem\",\"position\":2,\"name\":\"\\u03a0\\u03c1\\u03bf\\u03c3\\u03ba\\u03bb\\u03ae\\u03c3\\u03b5\\u03b9\\u03c2 \\u0394\\u03b7\\u03bc\\u03bf\\u03c4\\u03b9\\u03ba\\u03bf\\u03cd \\u03a3\\u03c5\\u03bc\\u03b2\\u03bf\\u03c5\\u03bb\\u03af\\u03bf\\u03c5\",\"item\":\"https:\\\/\\\/serifos.gr\\\/en\\\/category\\\/proskliseis_dimotikou_symvouliou\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/serifos.gr\\\/en\\\/%cf%80%cf%81%ce%bf%cf%83%ce%ba%ce%bb%ce%b7%cf%83%ce%b7-%cf%83%cf%85%ce%bd%ce%b5%ce%b4%cf%81%ce%b9%ce%b1%cf%83%ce%b7%cf%83-2%ce%bf%cf%85-%ce%b4%ce%b7%ce%bc%ce%bf%cf%84%ce%b9%ce%ba%ce%bf%cf%85-%cf%83\\\/#listItem\",\"name\":\"\\u03a0\\u03a1\\u039f\\u03a3\\u039a\\u039b\\u0397\\u03a3\\u0397 \\u03a3\\u03a5\\u039d\\u0395\\u0394\\u03a1\\u0399\\u0391\\u03a3\\u0397\\u03a3 2\\u03bf\\u03c5 \\u0394\\u0397\\u039c\\u039f\\u03a4\\u0399\\u039a\\u039f\\u03a5 \\u03a3\\u03a5\\u039c\\u0392\\u039f\\u03a5\\u039b\\u0399\\u039f\\u03a5 2023.\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/serifos.gr\\\/en#listItem\",\"name\":\"Home\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/serifos.gr\\\/en\\\/%cf%80%cf%81%ce%bf%cf%83%ce%ba%ce%bb%ce%b7%cf%83%ce%b7-%cf%83%cf%85%ce%bd%ce%b5%ce%b4%cf%81%ce%b9%ce%b1%cf%83%ce%b7%cf%83-2%ce%bf%cf%85-%ce%b4%ce%b7%ce%bc%ce%bf%cf%84%ce%b9%ce%ba%ce%bf%cf%85-%cf%83\\\/#listItem\",\"position\":3,\"name\":\"\\u03a0\\u03a1\\u039f\\u03a3\\u039a\\u039b\\u0397\\u03a3\\u0397 \\u03a3\\u03a5\\u039d\\u0395\\u0394\\u03a1\\u0399\\u0391\\u03a3\\u0397\\u03a3 2\\u03bf\\u03c5 \\u0394\\u0397\\u039c\\u039f\\u03a4\\u0399\\u039a\\u039f\\u03a5 \\u03a3\\u03a5\\u039c\\u0392\\u039f\\u03a5\\u039b\\u0399\\u039f\\u03a5 2023.\",\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/serifos.gr\\\/en\\\/category\\\/proskliseis_dimotikou_symvouliou\\\/#listItem\",\"name\":\"\\u03a0\\u03c1\\u03bf\\u03c3\\u03ba\\u03bb\\u03ae\\u03c3\\u03b5\\u03b9\\u03c2 \\u0394\\u03b7\\u03bc\\u03bf\\u03c4\\u03b9\\u03ba\\u03bf\\u03cd \\u03a3\\u03c5\\u03bc\\u03b2\\u03bf\\u03c5\\u03bb\\u03af\\u03bf\\u03c5\"}}]},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/serifos.gr\\\/en\\\/#organization\",\"name\":\"Serifos.gr\",\"description\":\"\\u0399\\u03c3\\u03c4\\u03bf\\u03c3\\u03b5\\u03bb\\u03af\\u03b4\\u03b1 \\u0394\\u03ae\\u03bc\\u03bf\\u03c5 \\u03a3\\u03b5\\u03c1\\u03af\\u03c6\\u03bf\\u03c5\",\"url\":\"https:\\\/\\\/serifos.gr\\\/en\\\/\",\"telephone\":\"+302281051210\",\"logo\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/serifos.gr\\\/wp-content\\\/uploads\\\/2017\\\/08\\\/Logo_final.png\",\"@id\":\"https:\\\/\\\/serifos.gr\\\/en\\\/%cf%80%cf%81%ce%bf%cf%83%ce%ba%ce%bb%ce%b7%cf%83%ce%b7-%cf%83%cf%85%ce%bd%ce%b5%ce%b4%cf%81%ce%b9%ce%b1%cf%83%ce%b7%cf%83-2%ce%bf%cf%85-%ce%b4%ce%b7%ce%bc%ce%bf%cf%84%ce%b9%ce%ba%ce%bf%cf%85-%cf%83\\\/#organizationLogo\",\"width\":181,\"height\":46},\"image\":{\"@id\":\"https:\\\/\\\/serifos.gr\\\/en\\\/%cf%80%cf%81%ce%bf%cf%83%ce%ba%ce%bb%ce%b7%cf%83%ce%b7-%cf%83%cf%85%ce%bd%ce%b5%ce%b4%cf%81%ce%b9%ce%b1%cf%83%ce%b7%cf%83-2%ce%bf%cf%85-%ce%b4%ce%b7%ce%bc%ce%bf%cf%84%ce%b9%ce%ba%ce%bf%cf%85-%cf%83\\\/#organizationLogo\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/dimosserifou\\\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/serifos.gr\\\/en\\\/author\\\/nslivanios\\\/#author\",\"url\":\"https:\\\/\\\/serifos.gr\\\/en\\\/author\\\/nslivanios\\\/\",\"name\":\"Stelios Livanios\",\"image\":{\"@type\":\"ImageObject\",\"@id\":\"https:\\\/\\\/serifos.gr\\\/en\\\/%cf%80%cf%81%ce%bf%cf%83%ce%ba%ce%bb%ce%b7%cf%83%ce%b7-%cf%83%cf%85%ce%bd%ce%b5%ce%b4%cf%81%ce%b9%ce%b1%cf%83%ce%b7%cf%83-2%ce%bf%cf%85-%ce%b4%ce%b7%ce%bc%ce%bf%cf%84%ce%b9%ce%ba%ce%bf%cf%85-%cf%83\\\/#authorImage\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/792605e3bbc86e998535857713ea857f9fd2f4916d59659513056a03e5d789f7?s=96&d=mm&r=g\",\"width\":96,\"height\":96,\"caption\":\"Stelios Livanios\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/serifos.gr\\\/en\\\/%cf%80%cf%81%ce%bf%cf%83%ce%ba%ce%bb%ce%b7%cf%83%ce%b7-%cf%83%cf%85%ce%bd%ce%b5%ce%b4%cf%81%ce%b9%ce%b1%cf%83%ce%b7%cf%83-2%ce%bf%cf%85-%ce%b4%ce%b7%ce%bc%ce%bf%cf%84%ce%b9%ce%ba%ce%bf%cf%85-%cf%83\\\/#webpage\",\"url\":\"https:\\\/\\\/serifos.gr\\\/en\\\/%cf%80%cf%81%ce%bf%cf%83%ce%ba%ce%bb%ce%b7%cf%83%ce%b7-%cf%83%cf%85%ce%bd%ce%b5%ce%b4%cf%81%ce%b9%ce%b1%cf%83%ce%b7%cf%83-2%ce%bf%cf%85-%ce%b4%ce%b7%ce%bc%ce%bf%cf%84%ce%b9%ce%ba%ce%bf%cf%85-%cf%83\\\/\",\"name\":\"\\u03a0\\u03a1\\u039f\\u03a3\\u039a\\u039b\\u0397\\u03a3\\u0397 \\u03a3\\u03a5\\u039d\\u0395\\u0394\\u03a1\\u0399\\u0391\\u03a3\\u0397\\u03a3 2\\u03bf\\u03c5 \\u0394\\u0397\\u039c\\u039f\\u03a4\\u0399\\u039a\\u039f\\u03a5 \\u03a3\\u03a5\\u039c\\u0392\\u039f\\u03a5\\u039b\\u0399\\u039f\\u03a5 2023. - Serifos.gr\",\"description\":\"\\u03a0\\u03a1\\u039f\\u03a3\\u039a\\u039b\\u0397\\u03a3\\u0397-\\u0394\\u03a3-2-2023\",\"inLanguage\":\"en-GB\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/serifos.gr\\\/en\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/serifos.gr\\\/en\\\/%cf%80%cf%81%ce%bf%cf%83%ce%ba%ce%bb%ce%b7%cf%83%ce%b7-%cf%83%cf%85%ce%bd%ce%b5%ce%b4%cf%81%ce%b9%ce%b1%cf%83%ce%b7%cf%83-2%ce%bf%cf%85-%ce%b4%ce%b7%ce%bc%ce%bf%cf%84%ce%b9%ce%ba%ce%bf%cf%85-%cf%83\\\/#breadcrumblist\"},\"author\":{\"@id\":\"https:\\\/\\\/serifos.gr\\\/en\\\/author\\\/nslivanios\\\/#author\"},\"creator\":{\"@id\":\"https:\\\/\\\/serifos.gr\\\/en\\\/author\\\/nslivanios\\\/#author\"},\"datePublished\":\"2023-02-10T10:41:00+03:00\",\"dateModified\":\"2023-05-12T10:45:18+03:00\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/serifos.gr\\\/en\\\/#website\",\"url\":\"https:\\\/\\\/serifos.gr\\\/en\\\/\",\"name\":\"Serifos.gr\",\"description\":\"\\u0399\\u03c3\\u03c4\\u03bf\\u03c3\\u03b5\\u03bb\\u03af\\u03b4\\u03b1 \\u0394\\u03ae\\u03bc\\u03bf\\u03c5 \\u03a3\\u03b5\\u03c1\\u03af\\u03c6\\u03bf\\u03c5\",\"inLanguage\":\"en-GB\",\"publisher\":{\"@id\":\"https:\\\/\\\/serifos.gr\\\/en\\\/#organization\"}}]}\n\t\t<\/script>\n\t\t<!-- All in One SEO -->\n\n","aioseo_head_json":{"title":"\u03a0\u03a1\u039f\u03a3\u039a\u039b\u0397\u03a3\u0397 \u03a3\u03a5\u039d\u0395\u0394\u03a1\u0399\u0391\u03a3\u0397\u03a3 2\u03bf\u03c5 \u0394\u0397\u039c\u039f\u03a4\u0399\u039a\u039f\u03a5 \u03a3\u03a5\u039c\u0392\u039f\u03a5\u039b\u0399\u039f\u03a5 2023. - Serifos.gr","description":"\u03a0\u03a1\u039f\u03a3\u039a\u039b\u0397\u03a3\u0397-\u0394\u03a3-2-2023","canonical_url":"https:\/\/serifos.gr\/en\/%cf%80%cf%81%ce%bf%cf%83%ce%ba%ce%bb%ce%b7%cf%83%ce%b7-%cf%83%cf%85%ce%bd%ce%b5%ce%b4%cf%81%ce%b9%ce%b1%cf%83%ce%b7%cf%83-2%ce%bf%cf%85-%ce%b4%ce%b7%ce%bc%ce%bf%cf%84%ce%b9%ce%ba%ce%bf%cf%85-%cf%83\/","robots":"max-image-preview:large","keywords":"","webmasterTools":{"miscellaneous":""},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"BlogPosting","@id":"https:\/\/serifos.gr\/en\/%cf%80%cf%81%ce%bf%cf%83%ce%ba%ce%bb%ce%b7%cf%83%ce%b7-%cf%83%cf%85%ce%bd%ce%b5%ce%b4%cf%81%ce%b9%ce%b1%cf%83%ce%b7%cf%83-2%ce%bf%cf%85-%ce%b4%ce%b7%ce%bc%ce%bf%cf%84%ce%b9%ce%ba%ce%bf%cf%85-%cf%83\/#blogposting","name":"\u03a0\u03a1\u039f\u03a3\u039a\u039b\u0397\u03a3\u0397 \u03a3\u03a5\u039d\u0395\u0394\u03a1\u0399\u0391\u03a3\u0397\u03a3 2\u03bf\u03c5 \u0394\u0397\u039c\u039f\u03a4\u0399\u039a\u039f\u03a5 \u03a3\u03a5\u039c\u0392\u039f\u03a5\u039b\u0399\u039f\u03a5 2023. - Serifos.gr","headline":"\u03a0\u03a1\u039f\u03a3\u039a\u039b\u0397\u03a3\u0397 \u03a3\u03a5\u039d\u0395\u0394\u03a1\u0399\u0391\u03a3\u0397\u03a3 2\u03bf\u03c5 \u0394\u0397\u039c\u039f\u03a4\u0399\u039a\u039f\u03a5 \u03a3\u03a5\u039c\u0392\u039f\u03a5\u039b\u0399\u039f\u03a5 2023.","author":{"@id":"https:\/\/serifos.gr\/en\/author\/nslivanios\/#author"},"publisher":{"@id":"https:\/\/serifos.gr\/en\/#organization"},"image":{"@type":"ImageObject","url":"https:\/\/serifos.gr\/wp-content\/uploads\/2017\/08\/Logo_final.png","@id":"https:\/\/serifos.gr\/en\/#articleImage","width":181,"height":46},"datePublished":"2023-02-10T10:41:00+03:00","dateModified":"2023-05-12T10:45:18+03:00","inLanguage":"en-GB","mainEntityOfPage":{"@id":"https:\/\/serifos.gr\/en\/%cf%80%cf%81%ce%bf%cf%83%ce%ba%ce%bb%ce%b7%cf%83%ce%b7-%cf%83%cf%85%ce%bd%ce%b5%ce%b4%cf%81%ce%b9%ce%b1%cf%83%ce%b7%cf%83-2%ce%bf%cf%85-%ce%b4%ce%b7%ce%bc%ce%bf%cf%84%ce%b9%ce%ba%ce%bf%cf%85-%cf%83\/#webpage"},"isPartOf":{"@id":"https:\/\/serifos.gr\/en\/%cf%80%cf%81%ce%bf%cf%83%ce%ba%ce%bb%ce%b7%cf%83%ce%b7-%cf%83%cf%85%ce%bd%ce%b5%ce%b4%cf%81%ce%b9%ce%b1%cf%83%ce%b7%cf%83-2%ce%bf%cf%85-%ce%b4%ce%b7%ce%bc%ce%bf%cf%84%ce%b9%ce%ba%ce%bf%cf%85-%cf%83\/#webpage"},"articleSection":"\u03a0\u03c1\u03bf\u03c3\u03ba\u03bb\u03ae\u03c3\u03b5\u03b9\u03c2 \u0394\u03b7\u03bc\u03bf\u03c4\u03b9\u03ba\u03bf\u03cd \u03a3\u03c5\u03bc\u03b2\u03bf\u03c5\u03bb\u03af\u03bf\u03c5"},{"@type":"BreadcrumbList","@id":"https:\/\/serifos.gr\/en\/%cf%80%cf%81%ce%bf%cf%83%ce%ba%ce%bb%ce%b7%cf%83%ce%b7-%cf%83%cf%85%ce%bd%ce%b5%ce%b4%cf%81%ce%b9%ce%b1%cf%83%ce%b7%cf%83-2%ce%bf%cf%85-%ce%b4%ce%b7%ce%bc%ce%bf%cf%84%ce%b9%ce%ba%ce%bf%cf%85-%cf%83\/#breadcrumblist","itemListElement":[{"@type":"ListItem","@id":"https:\/\/serifos.gr\/en#listItem","position":1,"name":"Home","item":"https:\/\/serifos.gr\/en","nextItem":{"@type":"ListItem","@id":"https:\/\/serifos.gr\/en\/category\/proskliseis_dimotikou_symvouliou\/#listItem","name":"\u03a0\u03c1\u03bf\u03c3\u03ba\u03bb\u03ae\u03c3\u03b5\u03b9\u03c2 \u0394\u03b7\u03bc\u03bf\u03c4\u03b9\u03ba\u03bf\u03cd \u03a3\u03c5\u03bc\u03b2\u03bf\u03c5\u03bb\u03af\u03bf\u03c5"}},{"@type":"ListItem","@id":"https:\/\/serifos.gr\/en\/category\/proskliseis_dimotikou_symvouliou\/#listItem","position":2,"name":"\u03a0\u03c1\u03bf\u03c3\u03ba\u03bb\u03ae\u03c3\u03b5\u03b9\u03c2 \u0394\u03b7\u03bc\u03bf\u03c4\u03b9\u03ba\u03bf\u03cd \u03a3\u03c5\u03bc\u03b2\u03bf\u03c5\u03bb\u03af\u03bf\u03c5","item":"https:\/\/serifos.gr\/en\/category\/proskliseis_dimotikou_symvouliou\/","nextItem":{"@type":"ListItem","@id":"https:\/\/serifos.gr\/en\/%cf%80%cf%81%ce%bf%cf%83%ce%ba%ce%bb%ce%b7%cf%83%ce%b7-%cf%83%cf%85%ce%bd%ce%b5%ce%b4%cf%81%ce%b9%ce%b1%cf%83%ce%b7%cf%83-2%ce%bf%cf%85-%ce%b4%ce%b7%ce%bc%ce%bf%cf%84%ce%b9%ce%ba%ce%bf%cf%85-%cf%83\/#listItem","name":"\u03a0\u03a1\u039f\u03a3\u039a\u039b\u0397\u03a3\u0397 \u03a3\u03a5\u039d\u0395\u0394\u03a1\u0399\u0391\u03a3\u0397\u03a3 2\u03bf\u03c5 \u0394\u0397\u039c\u039f\u03a4\u0399\u039a\u039f\u03a5 \u03a3\u03a5\u039c\u0392\u039f\u03a5\u039b\u0399\u039f\u03a5 2023."},"previousItem":{"@type":"ListItem","@id":"https:\/\/serifos.gr\/en#listItem","name":"Home"}},{"@type":"ListItem","@id":"https:\/\/serifos.gr\/en\/%cf%80%cf%81%ce%bf%cf%83%ce%ba%ce%bb%ce%b7%cf%83%ce%b7-%cf%83%cf%85%ce%bd%ce%b5%ce%b4%cf%81%ce%b9%ce%b1%cf%83%ce%b7%cf%83-2%ce%bf%cf%85-%ce%b4%ce%b7%ce%bc%ce%bf%cf%84%ce%b9%ce%ba%ce%bf%cf%85-%cf%83\/#listItem","position":3,"name":"\u03a0\u03a1\u039f\u03a3\u039a\u039b\u0397\u03a3\u0397 \u03a3\u03a5\u039d\u0395\u0394\u03a1\u0399\u0391\u03a3\u0397\u03a3 2\u03bf\u03c5 \u0394\u0397\u039c\u039f\u03a4\u0399\u039a\u039f\u03a5 \u03a3\u03a5\u039c\u0392\u039f\u03a5\u039b\u0399\u039f\u03a5 2023.","previousItem":{"@type":"ListItem","@id":"https:\/\/serifos.gr\/en\/category\/proskliseis_dimotikou_symvouliou\/#listItem","name":"\u03a0\u03c1\u03bf\u03c3\u03ba\u03bb\u03ae\u03c3\u03b5\u03b9\u03c2 \u0394\u03b7\u03bc\u03bf\u03c4\u03b9\u03ba\u03bf\u03cd \u03a3\u03c5\u03bc\u03b2\u03bf\u03c5\u03bb\u03af\u03bf\u03c5"}}]},{"@type":"Organization","@id":"https:\/\/serifos.gr\/en\/#organization","name":"Serifos.gr","description":"\u0399\u03c3\u03c4\u03bf\u03c3\u03b5\u03bb\u03af\u03b4\u03b1 \u0394\u03ae\u03bc\u03bf\u03c5 \u03a3\u03b5\u03c1\u03af\u03c6\u03bf\u03c5","url":"https:\/\/serifos.gr\/en\/","telephone":"+302281051210","logo":{"@type":"ImageObject","url":"https:\/\/serifos.gr\/wp-content\/uploads\/2017\/08\/Logo_final.png","@id":"https:\/\/serifos.gr\/en\/%cf%80%cf%81%ce%bf%cf%83%ce%ba%ce%bb%ce%b7%cf%83%ce%b7-%cf%83%cf%85%ce%bd%ce%b5%ce%b4%cf%81%ce%b9%ce%b1%cf%83%ce%b7%cf%83-2%ce%bf%cf%85-%ce%b4%ce%b7%ce%bc%ce%bf%cf%84%ce%b9%ce%ba%ce%bf%cf%85-%cf%83\/#organizationLogo","width":181,"height":46},"image":{"@id":"https:\/\/serifos.gr\/en\/%cf%80%cf%81%ce%bf%cf%83%ce%ba%ce%bb%ce%b7%cf%83%ce%b7-%cf%83%cf%85%ce%bd%ce%b5%ce%b4%cf%81%ce%b9%ce%b1%cf%83%ce%b7%cf%83-2%ce%bf%cf%85-%ce%b4%ce%b7%ce%bc%ce%bf%cf%84%ce%b9%ce%ba%ce%bf%cf%85-%cf%83\/#organizationLogo"},"sameAs":["https:\/\/www.facebook.com\/dimosserifou\/"]},{"@type":"Person","@id":"https:\/\/serifos.gr\/en\/author\/nslivanios\/#author","url":"https:\/\/serifos.gr\/en\/author\/nslivanios\/","name":"Stelios Livanios","image":{"@type":"ImageObject","@id":"https:\/\/serifos.gr\/en\/%cf%80%cf%81%ce%bf%cf%83%ce%ba%ce%bb%ce%b7%cf%83%ce%b7-%cf%83%cf%85%ce%bd%ce%b5%ce%b4%cf%81%ce%b9%ce%b1%cf%83%ce%b7%cf%83-2%ce%bf%cf%85-%ce%b4%ce%b7%ce%bc%ce%bf%cf%84%ce%b9%ce%ba%ce%bf%cf%85-%cf%83\/#authorImage","url":"https:\/\/secure.gravatar.com\/avatar\/792605e3bbc86e998535857713ea857f9fd2f4916d59659513056a03e5d789f7?s=96&d=mm&r=g","width":96,"height":96,"caption":"Stelios Livanios"}},{"@type":"WebPage","@id":"https:\/\/serifos.gr\/en\/%cf%80%cf%81%ce%bf%cf%83%ce%ba%ce%bb%ce%b7%cf%83%ce%b7-%cf%83%cf%85%ce%bd%ce%b5%ce%b4%cf%81%ce%b9%ce%b1%cf%83%ce%b7%cf%83-2%ce%bf%cf%85-%ce%b4%ce%b7%ce%bc%ce%bf%cf%84%ce%b9%ce%ba%ce%bf%cf%85-%cf%83\/#webpage","url":"https:\/\/serifos.gr\/en\/%cf%80%cf%81%ce%bf%cf%83%ce%ba%ce%bb%ce%b7%cf%83%ce%b7-%cf%83%cf%85%ce%bd%ce%b5%ce%b4%cf%81%ce%b9%ce%b1%cf%83%ce%b7%cf%83-2%ce%bf%cf%85-%ce%b4%ce%b7%ce%bc%ce%bf%cf%84%ce%b9%ce%ba%ce%bf%cf%85-%cf%83\/","name":"\u03a0\u03a1\u039f\u03a3\u039a\u039b\u0397\u03a3\u0397 \u03a3\u03a5\u039d\u0395\u0394\u03a1\u0399\u0391\u03a3\u0397\u03a3 2\u03bf\u03c5 \u0394\u0397\u039c\u039f\u03a4\u0399\u039a\u039f\u03a5 \u03a3\u03a5\u039c\u0392\u039f\u03a5\u039b\u0399\u039f\u03a5 2023. - Serifos.gr","description":"\u03a0\u03a1\u039f\u03a3\u039a\u039b\u0397\u03a3\u0397-\u0394\u03a3-2-2023","inLanguage":"en-GB","isPartOf":{"@id":"https:\/\/serifos.gr\/en\/#website"},"breadcrumb":{"@id":"https:\/\/serifos.gr\/en\/%cf%80%cf%81%ce%bf%cf%83%ce%ba%ce%bb%ce%b7%cf%83%ce%b7-%cf%83%cf%85%ce%bd%ce%b5%ce%b4%cf%81%ce%b9%ce%b1%cf%83%ce%b7%cf%83-2%ce%bf%cf%85-%ce%b4%ce%b7%ce%bc%ce%bf%cf%84%ce%b9%ce%ba%ce%bf%cf%85-%cf%83\/#breadcrumblist"},"author":{"@id":"https:\/\/serifos.gr\/en\/author\/nslivanios\/#author"},"creator":{"@id":"https:\/\/serifos.gr\/en\/author\/nslivanios\/#author"},"datePublished":"2023-02-10T10:41:00+03:00","dateModified":"2023-05-12T10:45:18+03:00"},{"@type":"WebSite","@id":"https:\/\/serifos.gr\/en\/#website","url":"https:\/\/serifos.gr\/en\/","name":"Serifos.gr","description":"\u0399\u03c3\u03c4\u03bf\u03c3\u03b5\u03bb\u03af\u03b4\u03b1 \u0394\u03ae\u03bc\u03bf\u03c5 \u03a3\u03b5\u03c1\u03af\u03c6\u03bf\u03c5","inLanguage":"en-GB","publisher":{"@id":"https:\/\/serifos.gr\/en\/#organization"}}]},"og:locale":"en_GB","og:site_name":"Serifos.gr - \u0399\u03c3\u03c4\u03bf\u03c3\u03b5\u03bb\u03af\u03b4\u03b1 \u0394\u03ae\u03bc\u03bf\u03c5 \u03a3\u03b5\u03c1\u03af\u03c6\u03bf\u03c5","og:type":"article","og:title":"\u03a0\u03a1\u039f\u03a3\u039a\u039b\u0397\u03a3\u0397 \u03a3\u03a5\u039d\u0395\u0394\u03a1\u0399\u0391\u03a3\u0397\u03a3 2\u03bf\u03c5 \u0394\u0397\u039c\u039f\u03a4\u0399\u039a\u039f\u03a5 \u03a3\u03a5\u039c\u0392\u039f\u03a5\u039b\u0399\u039f\u03a5 2023. - Serifos.gr","og:description":"\u03a0\u03a1\u039f\u03a3\u039a\u039b\u0397\u03a3\u0397-\u0394\u03a3-2-2023","og:url":"https:\/\/serifos.gr\/en\/%cf%80%cf%81%ce%bf%cf%83%ce%ba%ce%bb%ce%b7%cf%83%ce%b7-%cf%83%cf%85%ce%bd%ce%b5%ce%b4%cf%81%ce%b9%ce%b1%cf%83%ce%b7%cf%83-2%ce%bf%cf%85-%ce%b4%ce%b7%ce%bc%ce%bf%cf%84%ce%b9%ce%ba%ce%bf%cf%85-%cf%83\/","og:image":"https:\/\/serifos.gr\/wp-content\/uploads\/2017\/08\/Logo_final.png","og:image:secure_url":"https:\/\/serifos.gr\/wp-content\/uploads\/2017\/08\/Logo_final.png","og:image:width":181,"og:image:height":46,"article:published_time":"2023-02-10T07:41:00+00:00","article:modified_time":"2023-05-12T07:45:18+00:00","article:publisher":"https:\/\/www.facebook.com\/dimosserifou\/","twitter:card":"summary","twitter:title":"\u03a0\u03a1\u039f\u03a3\u039a\u039b\u0397\u03a3\u0397 \u03a3\u03a5\u039d\u0395\u0394\u03a1\u0399\u0391\u03a3\u0397\u03a3 2\u03bf\u03c5 \u0394\u0397\u039c\u039f\u03a4\u0399\u039a\u039f\u03a5 \u03a3\u03a5\u039c\u0392\u039f\u03a5\u039b\u0399\u039f\u03a5 2023. - Serifos.gr","twitter:description":"\u03a0\u03a1\u039f\u03a3\u039a\u039b\u0397\u03a3\u0397-\u0394\u03a3-2-2023","twitter:image":"https:\/\/serifos.gr\/wp-content\/uploads\/2017\/08\/Logo_final.png"},"aioseo_meta_data":{"post_id":"7035","title":null,"description":null,"keywords":[],"keyphrases":{"focus":{"keyphrase":"","score":0,"analysis":{"keyphraseInTitle":{"score":0,"maxScore":9,"error":1}}},"additional":[]},"primary_term":null,"canonical_url":null,"og_title":null,"og_description":null,"og_object_type":"default","og_image_type":"default","og_image_url":null,"og_image_width":null,"og_image_height":null,"og_image_custom_url":null,"og_image_custom_fields":null,"og_video":"","og_custom_url":null,"og_article_section":null,"og_article_tags":[],"twitter_use_og":false,"twitter_card":"default","twitter_image_type":"default","twitter_image_url":null,"twitter_image_custom_url":null,"twitter_image_custom_fields":null,"twitter_title":null,"twitter_description":null,"schema":{"blockGraphs":[],"customGraphs":[],"default":{"data":{"Article":{"id":"#aioseo-article-65bbca4908da1","slug":"article","graphName":"Article","label":"Article","properties":{"type":"BlogPosting","name":"#post_title","headline":"#post_title","description":"#post_excerpt","image":"","keywords":"","author":{"name":"#author_name","url":"#author_url"},"dates":{"include":true,"datePublished":"","dateModified":""}}},"Course":[],"Dataset":[],"FAQPage":[],"Movie":[],"Person":[],"Product":[],"ProductReview":[],"Car":[],"Recipe":[],"Service":[],"SoftwareApplication":[],"WebPage":[]},"graphName":"Article","isEnabled":true},"graphs":[]},"schema_type":"default","schema_type_options":"{\"article\":{\"articleType\":\"BlogPosting\"},\"course\":{\"name\":\"\",\"description\":\"\",\"provider\":\"\"},\"faq\":{\"pages\":[]},\"product\":{\"reviews\":[]},\"recipe\":{\"ingredients\":[],\"instructions\":[],\"keywords\":[]},\"software\":{\"reviews\":[],\"operatingSystems\":[]},\"webPage\":{\"webPageType\":\"WebPage\"}}","pillar_content":false,"robots_default":true,"robots_noindex":false,"robots_noarchive":false,"robots_nosnippet":false,"robots_nofollow":false,"robots_noimageindex":false,"robots_noodp":false,"robots_notranslate":false,"robots_max_snippet":"-1","robots_max_videopreview":"-1","robots_max_imagepreview":"large","priority":null,"frequency":"default","local_seo":null,"breadcrumb_settings":null,"limit_modified_date":false,"ai":null,"created":"2023-05-12 07:44:59","updated":"2026-03-12 06:27:46","focus_keyword":null,"additional_keywords":null,"truseo_locale":null,"seo_analyzer_scan_date":null},"_links":{"self":[{"href":"https:\/\/serifos.gr\/en\/wp-json\/wp\/v2\/posts\/7035","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/serifos.gr\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/serifos.gr\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/serifos.gr\/en\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/serifos.gr\/en\/wp-json\/wp\/v2\/comments?post=7035"}],"version-history":[{"count":1,"href":"https:\/\/serifos.gr\/en\/wp-json\/wp\/v2\/posts\/7035\/revisions"}],"predecessor-version":[{"id":7037,"href":"https:\/\/serifos.gr\/en\/wp-json\/wp\/v2\/posts\/7035\/revisions\/7037"}],"wp:attachment":[{"href":"https:\/\/serifos.gr\/en\/wp-json\/wp\/v2\/media?parent=7035"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/serifos.gr\/en\/wp-json\/wp\/v2\/categories?post=7035"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/serifos.gr\/en\/wp-json\/wp\/v2\/tags?post=7035"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}