{"id":5359,"date":"2021-07-30T10:11:12","date_gmt":"2021-07-30T07:11:12","guid":{"rendered":"https:\/\/serifos.gr\/?p=5359"},"modified":"2021-07-30T10:11:13","modified_gmt":"2021-07-30T07:11:13","slug":"%cf%80%cf%81%ce%bf%cf%83%ce%ba%ce%bb%ce%b7%cf%83%ce%b7-%ce%b5%ce%ba%ce%b4%ce%b7%ce%bb%cf%89%cf%83%ce%b7%cf%83-%ce%b5%ce%bd%ce%b4%ce%b9%ce%b1%cf%86%ce%b5%cf%81%ce%bf%ce%bd%cf%84%ce%bf%cf%83-%cf%85-28","status":"publish","type":"post","link":"https:\/\/serifos.gr\/en\/%cf%80%cf%81%ce%bf%cf%83%ce%ba%ce%bb%ce%b7%cf%83%ce%b7-%ce%b5%ce%ba%ce%b4%ce%b7%ce%bb%cf%89%cf%83%ce%b7%cf%83-%ce%b5%ce%bd%ce%b4%ce%b9%ce%b1%cf%86%ce%b5%cf%81%ce%bf%ce%bd%cf%84%ce%bf%cf%83-%cf%85-28\/","title":{"rendered":"\u03a0\u03a1\u039f\u03a3\u039a\u039b\u0397\u03a3\u0397 \u0395\u039a\u0394\u0397\u039b\u03a9\u03a3\u0397\u03a3 \u0395\u039d\u0394\u0399\u0391\u03a6\u0395\u03a1\u039f\u039d\u03a4\u039f\u03a3 \u03a5\u03a0\u039f\u0392\u039f\u039b\u0397\u03a3 \u03a0\u03a1\u039f\u03a3\u03a6\u039f\u03a1\u03a9\u039d \u0393\u0399\u0391 \u03a4\u0397\u039d  \u03a0\u03a1\u039f\u039c\u0397\u0398\u0395\u0399\u0391 \u0395\u0399\u0394\u0399\u039a\u039f\u03a5 \u039b\u039f\u0393\u0399\u03a3\u039c\u0399\u039a\u039f\u03a5 SMART CITY BI  \u0393\u0399\u0391 \u039f\u0399\u039a\u039f\u039d\u039f\u039c\u0399\u039a\u0397 \u0394\u0399\u0391\u03a7\u0395\u0399\u03a1\u0399\u03a3\u0397."},"content":{"rendered":"<div class=\"wp-block-pdfemb-pdf-embedder-viewer\"><a href=\"https:\/\/serifos.gr\/wp-content\/uploads\/2021\/07\/\u03a0\u03c1\u03cc\u03c3\u03ba\u03bb\u03b7\u03c3\u03b7-SMART-CITY.pdf\" class=\"pdfemb-viewer\" style=\"\" data-width=\"max\" data-height=\"max\" data-toolbar=\"bottom\" data-toolbar-fixed=\"off\">\u03a0\u03c1\u03cc\u03c3\u03ba\u03bb\u03b7\u03c3\u03b7-SMART-CITY<\/a><\/div>\n<p class=\"wp-block-pdfemb-pdf-embedder-viewer\"><\/p>","protected":false},"excerpt":{"rendered":"","protected":false},"author":2,"featured_media":0,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_monsterinsights_skip_tracking":false,"footnotes":"","_links_to":"","_links_to_target":""},"categories":[86],"tags":[],"class_list":["post-5359","post","type-post","status-publish","format-standard","hentry","category-86"],"aioseo_notices":[],"aioseo_head":"\n\t\t<!-- All in One SEO 5.0.0.1 - aioseo.com -->\n\t<meta name=\"description\" content=\"\u03a0\u03c1\u03cc\u03c3\u03ba\u03bb\u03b7\u03c3\u03b7-SMART-CITY\" \/>\n\t<meta name=\"robots\" content=\"max-image-preview:large\" \/>\n\t<meta name=\"author\" content=\"Stelios Livanios\"\/>\n\t<link rel=\"canonical\" href=\"https:\/\/serifos.gr\/en\/%cf%80%cf%81%ce%bf%cf%83%ce%ba%ce%bb%ce%b7%cf%83%ce%b7-%ce%b5%ce%ba%ce%b4%ce%b7%ce%bb%cf%89%cf%83%ce%b7%cf%83-%ce%b5%ce%bd%ce%b4%ce%b9%ce%b1%cf%86%ce%b5%cf%81%ce%bf%ce%bd%cf%84%ce%bf%cf%83-%cf%85-28\/\" \/>\n\t<meta name=\"generator\" content=\"All in One SEO (AIOSEO) 5.0.0.1\" \/>\n\t\t<meta property=\"og:locale\" content=\"en_GB\" \/>\n\t\t<meta property=\"og:site_name\" content=\"Serifos.gr - \u0399\u03c3\u03c4\u03bf\u03c3\u03b5\u03bb\u03af\u03b4\u03b1 \u0394\u03ae\u03bc\u03bf\u03c5 \u03a3\u03b5\u03c1\u03af\u03c6\u03bf\u03c5\" \/>\n\t\t<meta property=\"og:type\" content=\"article\" \/>\n\t\t<meta property=\"og:title\" content=\"\u03a0\u03a1\u039f\u03a3\u039a\u039b\u0397\u03a3\u0397 \u0395\u039a\u0394\u0397\u039b\u03a9\u03a3\u0397\u03a3 \u0395\u039d\u0394\u0399\u0391\u03a6\u0395\u03a1\u039f\u039d\u03a4\u039f\u03a3 \u03a5\u03a0\u039f\u0392\u039f\u039b\u0397\u03a3 \u03a0\u03a1\u039f\u03a3\u03a6\u039f\u03a1\u03a9\u039d \u0393\u0399\u0391 \u03a4\u0397\u039d \u03a0\u03a1\u039f\u039c\u0397\u0398\u0395\u0399\u0391 \u0395\u0399\u0394\u0399\u039a\u039f\u03a5 \u039b\u039f\u0393\u0399\u03a3\u039c\u0399\u039a\u039f\u03a5 SMART CITY BI \u0393\u0399\u0391 \u039f\u0399\u039a\u039f\u039d\u039f\u039c\u0399\u039a\u0397 \u0394\u0399\u0391\u03a7\u0395\u0399\u03a1\u0399\u03a3\u0397. - Serifos.gr\" \/>\n\t\t<meta property=\"og:description\" content=\"\u03a0\u03c1\u03cc\u03c3\u03ba\u03bb\u03b7\u03c3\u03b7-SMART-CITY\" \/>\n\t\t<meta property=\"og:url\" content=\"https:\/\/serifos.gr\/en\/%cf%80%cf%81%ce%bf%cf%83%ce%ba%ce%bb%ce%b7%cf%83%ce%b7-%ce%b5%ce%ba%ce%b4%ce%b7%ce%bb%cf%89%cf%83%ce%b7%cf%83-%ce%b5%ce%bd%ce%b4%ce%b9%ce%b1%cf%86%ce%b5%cf%81%ce%bf%ce%bd%cf%84%ce%bf%cf%83-%cf%85-28\/\" \/>\n\t\t<meta property=\"og:image\" content=\"https:\/\/serifos.gr\/wp-content\/uploads\/2017\/08\/Logo_final.png\" \/>\n\t\t<meta property=\"og:image:secure_url\" content=\"https:\/\/serifos.gr\/wp-content\/uploads\/2017\/08\/Logo_final.png\" \/>\n\t\t<meta property=\"og:image:width\" content=\"181\" \/>\n\t\t<meta property=\"og:image:height\" content=\"46\" \/>\n\t\t<meta property=\"article:published_time\" content=\"2021-07-30T07:11:12+00:00\" \/>\n\t\t<meta property=\"article:modified_time\" content=\"2021-07-30T07:11:13+00:00\" \/>\n\t\t<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/dimosserifou\/\" \/>\n\t\t<meta name=\"twitter:card\" content=\"summary\" \/>\n\t\t<meta name=\"twitter:title\" content=\"\u03a0\u03a1\u039f\u03a3\u039a\u039b\u0397\u03a3\u0397 \u0395\u039a\u0394\u0397\u039b\u03a9\u03a3\u0397\u03a3 \u0395\u039d\u0394\u0399\u0391\u03a6\u0395\u03a1\u039f\u039d\u03a4\u039f\u03a3 \u03a5\u03a0\u039f\u0392\u039f\u039b\u0397\u03a3 \u03a0\u03a1\u039f\u03a3\u03a6\u039f\u03a1\u03a9\u039d \u0393\u0399\u0391 \u03a4\u0397\u039d \u03a0\u03a1\u039f\u039c\u0397\u0398\u0395\u0399\u0391 \u0395\u0399\u0394\u0399\u039a\u039f\u03a5 \u039b\u039f\u0393\u0399\u03a3\u039c\u0399\u039a\u039f\u03a5 SMART CITY BI \u0393\u0399\u0391 \u039f\u0399\u039a\u039f\u039d\u039f\u039c\u0399\u039a\u0397 \u0394\u0399\u0391\u03a7\u0395\u0399\u03a1\u0399\u03a3\u0397. - Serifos.gr\" \/>\n\t\t<meta name=\"twitter:description\" content=\"\u03a0\u03c1\u03cc\u03c3\u03ba\u03bb\u03b7\u03c3\u03b7-SMART-CITY\" \/>\n\t\t<meta name=\"twitter:image\" content=\"https:\/\/serifos.gr\/wp-content\/uploads\/2017\/08\/Logo_final.png\" \/>\n\t\t<script type=\"application\/ld+json\" class=\"aioseo-schema\">\n\t\t\t{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"BlogPosting\",\"@id\":\"https:\\\/\\\/serifos.gr\\\/en\\\/%cf%80%cf%81%ce%bf%cf%83%ce%ba%ce%bb%ce%b7%cf%83%ce%b7-%ce%b5%ce%ba%ce%b4%ce%b7%ce%bb%cf%89%cf%83%ce%b7%cf%83-%ce%b5%ce%bd%ce%b4%ce%b9%ce%b1%cf%86%ce%b5%cf%81%ce%bf%ce%bd%cf%84%ce%bf%cf%83-%cf%85-28\\\/#blogposting\",\"name\":\"\\u03a0\\u03a1\\u039f\\u03a3\\u039a\\u039b\\u0397\\u03a3\\u0397 \\u0395\\u039a\\u0394\\u0397\\u039b\\u03a9\\u03a3\\u0397\\u03a3 \\u0395\\u039d\\u0394\\u0399\\u0391\\u03a6\\u0395\\u03a1\\u039f\\u039d\\u03a4\\u039f\\u03a3 \\u03a5\\u03a0\\u039f\\u0392\\u039f\\u039b\\u0397\\u03a3 \\u03a0\\u03a1\\u039f\\u03a3\\u03a6\\u039f\\u03a1\\u03a9\\u039d \\u0393\\u0399\\u0391 \\u03a4\\u0397\\u039d \\u03a0\\u03a1\\u039f\\u039c\\u0397\\u0398\\u0395\\u0399\\u0391 \\u0395\\u0399\\u0394\\u0399\\u039a\\u039f\\u03a5 \\u039b\\u039f\\u0393\\u0399\\u03a3\\u039c\\u0399\\u039a\\u039f\\u03a5 SMART CITY BI \\u0393\\u0399\\u0391 \\u039f\\u0399\\u039a\\u039f\\u039d\\u039f\\u039c\\u0399\\u039a\\u0397 \\u0394\\u0399\\u0391\\u03a7\\u0395\\u0399\\u03a1\\u0399\\u03a3\\u0397. - Serifos.gr\",\"headline\":\"\\u03a0\\u03a1\\u039f\\u03a3\\u039a\\u039b\\u0397\\u03a3\\u0397 \\u0395\\u039a\\u0394\\u0397\\u039b\\u03a9\\u03a3\\u0397\\u03a3 \\u0395\\u039d\\u0394\\u0399\\u0391\\u03a6\\u0395\\u03a1\\u039f\\u039d\\u03a4\\u039f\\u03a3 \\u03a5\\u03a0\\u039f\\u0392\\u039f\\u039b\\u0397\\u03a3 \\u03a0\\u03a1\\u039f\\u03a3\\u03a6\\u039f\\u03a1\\u03a9\\u039d \\u0393\\u0399\\u0391 \\u03a4\\u0397\\u039d  \\u03a0\\u03a1\\u039f\\u039c\\u0397\\u0398\\u0395\\u0399\\u0391 \\u0395\\u0399\\u0394\\u0399\\u039a\\u039f\\u03a5 \\u039b\\u039f\\u0393\\u0399\\u03a3\\u039c\\u0399\\u039a\\u039f\\u03a5 SMART CITY BI  \\u0393\\u0399\\u0391 \\u039f\\u0399\\u039a\\u039f\\u039d\\u039f\\u039c\\u0399\\u039a\\u0397 \\u0394\\u0399\\u0391\\u03a7\\u0395\\u0399\\u03a1\\u0399\\u03a3\\u0397.\",\"author\":{\"@id\":\"https:\\\/\\\/serifos.gr\\\/en\\\/author\\\/nslivanios\\\/#author\"},\"publisher\":{\"@id\":\"https:\\\/\\\/serifos.gr\\\/en\\\/#organization\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/serifos.gr\\\/wp-content\\\/uploads\\\/2017\\\/08\\\/Logo_final.png\",\"@id\":\"https:\\\/\\\/serifos.gr\\\/en\\\/#articleImage\",\"width\":181,\"height\":46},\"datePublished\":\"2021-07-30T10:11:12+03:00\",\"dateModified\":\"2021-07-30T10:11:13+03:00\",\"inLanguage\":\"en-GB\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/serifos.gr\\\/en\\\/%cf%80%cf%81%ce%bf%cf%83%ce%ba%ce%bb%ce%b7%cf%83%ce%b7-%ce%b5%ce%ba%ce%b4%ce%b7%ce%bb%cf%89%cf%83%ce%b7%cf%83-%ce%b5%ce%bd%ce%b4%ce%b9%ce%b1%cf%86%ce%b5%cf%81%ce%bf%ce%bd%cf%84%ce%bf%cf%83-%cf%85-28\\\/#webpage\"},\"isPartOf\":{\"@id\":\"https:\\\/\\\/serifos.gr\\\/en\\\/%cf%80%cf%81%ce%bf%cf%83%ce%ba%ce%bb%ce%b7%cf%83%ce%b7-%ce%b5%ce%ba%ce%b4%ce%b7%ce%bb%cf%89%cf%83%ce%b7%cf%83-%ce%b5%ce%bd%ce%b4%ce%b9%ce%b1%cf%86%ce%b5%cf%81%ce%bf%ce%bd%cf%84%ce%bf%cf%83-%cf%85-28\\\/#webpage\"},\"articleSection\":\"\\u0391\\u03bd\\u03b1\\u03ba\\u03bf\\u03b9\\u03bd\\u03ce\\u03c3\\u03b5\\u03b9\\u03c2\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/serifos.gr\\\/en\\\/%cf%80%cf%81%ce%bf%cf%83%ce%ba%ce%bb%ce%b7%cf%83%ce%b7-%ce%b5%ce%ba%ce%b4%ce%b7%ce%bb%cf%89%cf%83%ce%b7%cf%83-%ce%b5%ce%bd%ce%b4%ce%b9%ce%b1%cf%86%ce%b5%cf%81%ce%bf%ce%bd%cf%84%ce%bf%cf%83-%cf%85-28\\\/#breadcrumblist\",\"itemListElement\":[{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/serifos.gr\\\/en#listItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/serifos.gr\\\/en\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/serifos.gr\\\/en\\\/category\\\/%ce%b1%ce%bd%ce%b1%ce%ba%ce%bf%ce%b9%ce%bd%cf%8e%cf%83%ce%b5%ce%b9%cf%82\\\/#listItem\",\"name\":\"\\u0391\\u03bd\\u03b1\\u03ba\\u03bf\\u03b9\\u03bd\\u03ce\\u03c3\\u03b5\\u03b9\\u03c2\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/serifos.gr\\\/en\\\/category\\\/%ce%b1%ce%bd%ce%b1%ce%ba%ce%bf%ce%b9%ce%bd%cf%8e%cf%83%ce%b5%ce%b9%cf%82\\\/#listItem\",\"position\":2,\"name\":\"\\u0391\\u03bd\\u03b1\\u03ba\\u03bf\\u03b9\\u03bd\\u03ce\\u03c3\\u03b5\\u03b9\\u03c2\",\"item\":\"https:\\\/\\\/serifos.gr\\\/en\\\/category\\\/%ce%b1%ce%bd%ce%b1%ce%ba%ce%bf%ce%b9%ce%bd%cf%8e%cf%83%ce%b5%ce%b9%cf%82\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/serifos.gr\\\/en\\\/%cf%80%cf%81%ce%bf%cf%83%ce%ba%ce%bb%ce%b7%cf%83%ce%b7-%ce%b5%ce%ba%ce%b4%ce%b7%ce%bb%cf%89%cf%83%ce%b7%cf%83-%ce%b5%ce%bd%ce%b4%ce%b9%ce%b1%cf%86%ce%b5%cf%81%ce%bf%ce%bd%cf%84%ce%bf%cf%83-%cf%85-28\\\/#listItem\",\"name\":\"\\u03a0\\u03a1\\u039f\\u03a3\\u039a\\u039b\\u0397\\u03a3\\u0397 \\u0395\\u039a\\u0394\\u0397\\u039b\\u03a9\\u03a3\\u0397\\u03a3 \\u0395\\u039d\\u0394\\u0399\\u0391\\u03a6\\u0395\\u03a1\\u039f\\u039d\\u03a4\\u039f\\u03a3 \\u03a5\\u03a0\\u039f\\u0392\\u039f\\u039b\\u0397\\u03a3 \\u03a0\\u03a1\\u039f\\u03a3\\u03a6\\u039f\\u03a1\\u03a9\\u039d \\u0393\\u0399\\u0391 \\u03a4\\u0397\\u039d  \\u03a0\\u03a1\\u039f\\u039c\\u0397\\u0398\\u0395\\u0399\\u0391 \\u0395\\u0399\\u0394\\u0399\\u039a\\u039f\\u03a5 \\u039b\\u039f\\u0393\\u0399\\u03a3\\u039c\\u0399\\u039a\\u039f\\u03a5 SMART CITY BI  \\u0393\\u0399\\u0391 \\u039f\\u0399\\u039a\\u039f\\u039d\\u039f\\u039c\\u0399\\u039a\\u0397 \\u0394\\u0399\\u0391\\u03a7\\u0395\\u0399\\u03a1\\u0399\\u03a3\\u0397.\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/serifos.gr\\\/en#listItem\",\"name\":\"Home\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/serifos.gr\\\/en\\\/%cf%80%cf%81%ce%bf%cf%83%ce%ba%ce%bb%ce%b7%cf%83%ce%b7-%ce%b5%ce%ba%ce%b4%ce%b7%ce%bb%cf%89%cf%83%ce%b7%cf%83-%ce%b5%ce%bd%ce%b4%ce%b9%ce%b1%cf%86%ce%b5%cf%81%ce%bf%ce%bd%cf%84%ce%bf%cf%83-%cf%85-28\\\/#listItem\",\"position\":3,\"name\":\"\\u03a0\\u03a1\\u039f\\u03a3\\u039a\\u039b\\u0397\\u03a3\\u0397 \\u0395\\u039a\\u0394\\u0397\\u039b\\u03a9\\u03a3\\u0397\\u03a3 \\u0395\\u039d\\u0394\\u0399\\u0391\\u03a6\\u0395\\u03a1\\u039f\\u039d\\u03a4\\u039f\\u03a3 \\u03a5\\u03a0\\u039f\\u0392\\u039f\\u039b\\u0397\\u03a3 \\u03a0\\u03a1\\u039f\\u03a3\\u03a6\\u039f\\u03a1\\u03a9\\u039d \\u0393\\u0399\\u0391 \\u03a4\\u0397\\u039d  \\u03a0\\u03a1\\u039f\\u039c\\u0397\\u0398\\u0395\\u0399\\u0391 \\u0395\\u0399\\u0394\\u0399\\u039a\\u039f\\u03a5 \\u039b\\u039f\\u0393\\u0399\\u03a3\\u039c\\u0399\\u039a\\u039f\\u03a5 SMART CITY BI  \\u0393\\u0399\\u0391 \\u039f\\u0399\\u039a\\u039f\\u039d\\u039f\\u039c\\u0399\\u039a\\u0397 \\u0394\\u0399\\u0391\\u03a7\\u0395\\u0399\\u03a1\\u0399\\u03a3\\u0397.\",\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/serifos.gr\\\/en\\\/category\\\/%ce%b1%ce%bd%ce%b1%ce%ba%ce%bf%ce%b9%ce%bd%cf%8e%cf%83%ce%b5%ce%b9%cf%82\\\/#listItem\",\"name\":\"\\u0391\\u03bd\\u03b1\\u03ba\\u03bf\\u03b9\\u03bd\\u03ce\\u03c3\\u03b5\\u03b9\\u03c2\"}}]},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/serifos.gr\\\/en\\\/#organization\",\"name\":\"Serifos.gr\",\"description\":\"\\u0399\\u03c3\\u03c4\\u03bf\\u03c3\\u03b5\\u03bb\\u03af\\u03b4\\u03b1 \\u0394\\u03ae\\u03bc\\u03bf\\u03c5 \\u03a3\\u03b5\\u03c1\\u03af\\u03c6\\u03bf\\u03c5\",\"url\":\"https:\\\/\\\/serifos.gr\\\/en\\\/\",\"telephone\":\"+302281051210\",\"logo\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/serifos.gr\\\/wp-content\\\/uploads\\\/2017\\\/08\\\/Logo_final.png\",\"@id\":\"https:\\\/\\\/serifos.gr\\\/en\\\/%cf%80%cf%81%ce%bf%cf%83%ce%ba%ce%bb%ce%b7%cf%83%ce%b7-%ce%b5%ce%ba%ce%b4%ce%b7%ce%bb%cf%89%cf%83%ce%b7%cf%83-%ce%b5%ce%bd%ce%b4%ce%b9%ce%b1%cf%86%ce%b5%cf%81%ce%bf%ce%bd%cf%84%ce%bf%cf%83-%cf%85-28\\\/#organizationLogo\",\"width\":181,\"height\":46},\"image\":{\"@id\":\"https:\\\/\\\/serifos.gr\\\/en\\\/%cf%80%cf%81%ce%bf%cf%83%ce%ba%ce%bb%ce%b7%cf%83%ce%b7-%ce%b5%ce%ba%ce%b4%ce%b7%ce%bb%cf%89%cf%83%ce%b7%cf%83-%ce%b5%ce%bd%ce%b4%ce%b9%ce%b1%cf%86%ce%b5%cf%81%ce%bf%ce%bd%cf%84%ce%bf%cf%83-%cf%85-28\\\/#organizationLogo\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/dimosserifou\\\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/serifos.gr\\\/en\\\/author\\\/nslivanios\\\/#author\",\"url\":\"https:\\\/\\\/serifos.gr\\\/en\\\/author\\\/nslivanios\\\/\",\"name\":\"Stelios Livanios\",\"image\":{\"@type\":\"ImageObject\",\"@id\":\"https:\\\/\\\/serifos.gr\\\/en\\\/%cf%80%cf%81%ce%bf%cf%83%ce%ba%ce%bb%ce%b7%cf%83%ce%b7-%ce%b5%ce%ba%ce%b4%ce%b7%ce%bb%cf%89%cf%83%ce%b7%cf%83-%ce%b5%ce%bd%ce%b4%ce%b9%ce%b1%cf%86%ce%b5%cf%81%ce%bf%ce%bd%cf%84%ce%bf%cf%83-%cf%85-28\\\/#authorImage\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/792605e3bbc86e998535857713ea857f9fd2f4916d59659513056a03e5d789f7?s=96&d=mm&r=g\",\"width\":96,\"height\":96,\"caption\":\"Stelios Livanios\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/serifos.gr\\\/en\\\/%cf%80%cf%81%ce%bf%cf%83%ce%ba%ce%bb%ce%b7%cf%83%ce%b7-%ce%b5%ce%ba%ce%b4%ce%b7%ce%bb%cf%89%cf%83%ce%b7%cf%83-%ce%b5%ce%bd%ce%b4%ce%b9%ce%b1%cf%86%ce%b5%cf%81%ce%bf%ce%bd%cf%84%ce%bf%cf%83-%cf%85-28\\\/#webpage\",\"url\":\"https:\\\/\\\/serifos.gr\\\/en\\\/%cf%80%cf%81%ce%bf%cf%83%ce%ba%ce%bb%ce%b7%cf%83%ce%b7-%ce%b5%ce%ba%ce%b4%ce%b7%ce%bb%cf%89%cf%83%ce%b7%cf%83-%ce%b5%ce%bd%ce%b4%ce%b9%ce%b1%cf%86%ce%b5%cf%81%ce%bf%ce%bd%cf%84%ce%bf%cf%83-%cf%85-28\\\/\",\"name\":\"\\u03a0\\u03a1\\u039f\\u03a3\\u039a\\u039b\\u0397\\u03a3\\u0397 \\u0395\\u039a\\u0394\\u0397\\u039b\\u03a9\\u03a3\\u0397\\u03a3 \\u0395\\u039d\\u0394\\u0399\\u0391\\u03a6\\u0395\\u03a1\\u039f\\u039d\\u03a4\\u039f\\u03a3 \\u03a5\\u03a0\\u039f\\u0392\\u039f\\u039b\\u0397\\u03a3 \\u03a0\\u03a1\\u039f\\u03a3\\u03a6\\u039f\\u03a1\\u03a9\\u039d \\u0393\\u0399\\u0391 \\u03a4\\u0397\\u039d \\u03a0\\u03a1\\u039f\\u039c\\u0397\\u0398\\u0395\\u0399\\u0391 \\u0395\\u0399\\u0394\\u0399\\u039a\\u039f\\u03a5 \\u039b\\u039f\\u0393\\u0399\\u03a3\\u039c\\u0399\\u039a\\u039f\\u03a5 SMART CITY BI \\u0393\\u0399\\u0391 \\u039f\\u0399\\u039a\\u039f\\u039d\\u039f\\u039c\\u0399\\u039a\\u0397 \\u0394\\u0399\\u0391\\u03a7\\u0395\\u0399\\u03a1\\u0399\\u03a3\\u0397. - Serifos.gr\",\"description\":\"\\u03a0\\u03c1\\u03cc\\u03c3\\u03ba\\u03bb\\u03b7\\u03c3\\u03b7-SMART-CITY\",\"inLanguage\":\"en-GB\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/serifos.gr\\\/en\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/serifos.gr\\\/en\\\/%cf%80%cf%81%ce%bf%cf%83%ce%ba%ce%bb%ce%b7%cf%83%ce%b7-%ce%b5%ce%ba%ce%b4%ce%b7%ce%bb%cf%89%cf%83%ce%b7%cf%83-%ce%b5%ce%bd%ce%b4%ce%b9%ce%b1%cf%86%ce%b5%cf%81%ce%bf%ce%bd%cf%84%ce%bf%cf%83-%cf%85-28\\\/#breadcrumblist\"},\"author\":{\"@id\":\"https:\\\/\\\/serifos.gr\\\/en\\\/author\\\/nslivanios\\\/#author\"},\"creator\":{\"@id\":\"https:\\\/\\\/serifos.gr\\\/en\\\/author\\\/nslivanios\\\/#author\"},\"datePublished\":\"2021-07-30T10:11:12+03:00\",\"dateModified\":\"2021-07-30T10:11:13+03:00\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/serifos.gr\\\/en\\\/#website\",\"url\":\"https:\\\/\\\/serifos.gr\\\/en\\\/\",\"name\":\"Serifos.gr\",\"description\":\"\\u0399\\u03c3\\u03c4\\u03bf\\u03c3\\u03b5\\u03bb\\u03af\\u03b4\\u03b1 \\u0394\\u03ae\\u03bc\\u03bf\\u03c5 \\u03a3\\u03b5\\u03c1\\u03af\\u03c6\\u03bf\\u03c5\",\"inLanguage\":\"en-GB\",\"publisher\":{\"@id\":\"https:\\\/\\\/serifos.gr\\\/en\\\/#organization\"}}]}\n\t\t<\/script>\n\t\t<!-- All in One SEO -->\n\n","aioseo_head_json":{"title":"\u03a0\u03a1\u039f\u03a3\u039a\u039b\u0397\u03a3\u0397 \u0395\u039a\u0394\u0397\u039b\u03a9\u03a3\u0397\u03a3 \u0395\u039d\u0394\u0399\u0391\u03a6\u0395\u03a1\u039f\u039d\u03a4\u039f\u03a3 \u03a5\u03a0\u039f\u0392\u039f\u039b\u0397\u03a3 \u03a0\u03a1\u039f\u03a3\u03a6\u039f\u03a1\u03a9\u039d \u0393\u0399\u0391 \u03a4\u0397\u039d \u03a0\u03a1\u039f\u039c\u0397\u0398\u0395\u0399\u0391 \u0395\u0399\u0394\u0399\u039a\u039f\u03a5 \u039b\u039f\u0393\u0399\u03a3\u039c\u0399\u039a\u039f\u03a5 SMART CITY BI \u0393\u0399\u0391 \u039f\u0399\u039a\u039f\u039d\u039f\u039c\u0399\u039a\u0397 \u0394\u0399\u0391\u03a7\u0395\u0399\u03a1\u0399\u03a3\u0397. - Serifos.gr","description":"\u03a0\u03c1\u03cc\u03c3\u03ba\u03bb\u03b7\u03c3\u03b7-SMART-CITY","canonical_url":"https:\/\/serifos.gr\/en\/%cf%80%cf%81%ce%bf%cf%83%ce%ba%ce%bb%ce%b7%cf%83%ce%b7-%ce%b5%ce%ba%ce%b4%ce%b7%ce%bb%cf%89%cf%83%ce%b7%cf%83-%ce%b5%ce%bd%ce%b4%ce%b9%ce%b1%cf%86%ce%b5%cf%81%ce%bf%ce%bd%cf%84%ce%bf%cf%83-%cf%85-28\/","robots":"max-image-preview:large","keywords":"","webmasterTools":{"miscellaneous":""},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"BlogPosting","@id":"https:\/\/serifos.gr\/en\/%cf%80%cf%81%ce%bf%cf%83%ce%ba%ce%bb%ce%b7%cf%83%ce%b7-%ce%b5%ce%ba%ce%b4%ce%b7%ce%bb%cf%89%cf%83%ce%b7%cf%83-%ce%b5%ce%bd%ce%b4%ce%b9%ce%b1%cf%86%ce%b5%cf%81%ce%bf%ce%bd%cf%84%ce%bf%cf%83-%cf%85-28\/#blogposting","name":"\u03a0\u03a1\u039f\u03a3\u039a\u039b\u0397\u03a3\u0397 \u0395\u039a\u0394\u0397\u039b\u03a9\u03a3\u0397\u03a3 \u0395\u039d\u0394\u0399\u0391\u03a6\u0395\u03a1\u039f\u039d\u03a4\u039f\u03a3 \u03a5\u03a0\u039f\u0392\u039f\u039b\u0397\u03a3 \u03a0\u03a1\u039f\u03a3\u03a6\u039f\u03a1\u03a9\u039d \u0393\u0399\u0391 \u03a4\u0397\u039d \u03a0\u03a1\u039f\u039c\u0397\u0398\u0395\u0399\u0391 \u0395\u0399\u0394\u0399\u039a\u039f\u03a5 \u039b\u039f\u0393\u0399\u03a3\u039c\u0399\u039a\u039f\u03a5 SMART CITY BI \u0393\u0399\u0391 \u039f\u0399\u039a\u039f\u039d\u039f\u039c\u0399\u039a\u0397 \u0394\u0399\u0391\u03a7\u0395\u0399\u03a1\u0399\u03a3\u0397. - Serifos.gr","headline":"\u03a0\u03a1\u039f\u03a3\u039a\u039b\u0397\u03a3\u0397 \u0395\u039a\u0394\u0397\u039b\u03a9\u03a3\u0397\u03a3 \u0395\u039d\u0394\u0399\u0391\u03a6\u0395\u03a1\u039f\u039d\u03a4\u039f\u03a3 \u03a5\u03a0\u039f\u0392\u039f\u039b\u0397\u03a3 \u03a0\u03a1\u039f\u03a3\u03a6\u039f\u03a1\u03a9\u039d \u0393\u0399\u0391 \u03a4\u0397\u039d  \u03a0\u03a1\u039f\u039c\u0397\u0398\u0395\u0399\u0391 \u0395\u0399\u0394\u0399\u039a\u039f\u03a5 \u039b\u039f\u0393\u0399\u03a3\u039c\u0399\u039a\u039f\u03a5 SMART CITY BI  \u0393\u0399\u0391 \u039f\u0399\u039a\u039f\u039d\u039f\u039c\u0399\u039a\u0397 \u0394\u0399\u0391\u03a7\u0395\u0399\u03a1\u0399\u03a3\u0397.","author":{"@id":"https:\/\/serifos.gr\/en\/author\/nslivanios\/#author"},"publisher":{"@id":"https:\/\/serifos.gr\/en\/#organization"},"image":{"@type":"ImageObject","url":"https:\/\/serifos.gr\/wp-content\/uploads\/2017\/08\/Logo_final.png","@id":"https:\/\/serifos.gr\/en\/#articleImage","width":181,"height":46},"datePublished":"2021-07-30T10:11:12+03:00","dateModified":"2021-07-30T10:11:13+03:00","inLanguage":"en-GB","mainEntityOfPage":{"@id":"https:\/\/serifos.gr\/en\/%cf%80%cf%81%ce%bf%cf%83%ce%ba%ce%bb%ce%b7%cf%83%ce%b7-%ce%b5%ce%ba%ce%b4%ce%b7%ce%bb%cf%89%cf%83%ce%b7%cf%83-%ce%b5%ce%bd%ce%b4%ce%b9%ce%b1%cf%86%ce%b5%cf%81%ce%bf%ce%bd%cf%84%ce%bf%cf%83-%cf%85-28\/#webpage"},"isPartOf":{"@id":"https:\/\/serifos.gr\/en\/%cf%80%cf%81%ce%bf%cf%83%ce%ba%ce%bb%ce%b7%cf%83%ce%b7-%ce%b5%ce%ba%ce%b4%ce%b7%ce%bb%cf%89%cf%83%ce%b7%cf%83-%ce%b5%ce%bd%ce%b4%ce%b9%ce%b1%cf%86%ce%b5%cf%81%ce%bf%ce%bd%cf%84%ce%bf%cf%83-%cf%85-28\/#webpage"},"articleSection":"\u0391\u03bd\u03b1\u03ba\u03bf\u03b9\u03bd\u03ce\u03c3\u03b5\u03b9\u03c2"},{"@type":"BreadcrumbList","@id":"https:\/\/serifos.gr\/en\/%cf%80%cf%81%ce%bf%cf%83%ce%ba%ce%bb%ce%b7%cf%83%ce%b7-%ce%b5%ce%ba%ce%b4%ce%b7%ce%bb%cf%89%cf%83%ce%b7%cf%83-%ce%b5%ce%bd%ce%b4%ce%b9%ce%b1%cf%86%ce%b5%cf%81%ce%bf%ce%bd%cf%84%ce%bf%cf%83-%cf%85-28\/#breadcrumblist","itemListElement":[{"@type":"ListItem","@id":"https:\/\/serifos.gr\/en#listItem","position":1,"name":"Home","item":"https:\/\/serifos.gr\/en","nextItem":{"@type":"ListItem","@id":"https:\/\/serifos.gr\/en\/category\/%ce%b1%ce%bd%ce%b1%ce%ba%ce%bf%ce%b9%ce%bd%cf%8e%cf%83%ce%b5%ce%b9%cf%82\/#listItem","name":"\u0391\u03bd\u03b1\u03ba\u03bf\u03b9\u03bd\u03ce\u03c3\u03b5\u03b9\u03c2"}},{"@type":"ListItem","@id":"https:\/\/serifos.gr\/en\/category\/%ce%b1%ce%bd%ce%b1%ce%ba%ce%bf%ce%b9%ce%bd%cf%8e%cf%83%ce%b5%ce%b9%cf%82\/#listItem","position":2,"name":"\u0391\u03bd\u03b1\u03ba\u03bf\u03b9\u03bd\u03ce\u03c3\u03b5\u03b9\u03c2","item":"https:\/\/serifos.gr\/en\/category\/%ce%b1%ce%bd%ce%b1%ce%ba%ce%bf%ce%b9%ce%bd%cf%8e%cf%83%ce%b5%ce%b9%cf%82\/","nextItem":{"@type":"ListItem","@id":"https:\/\/serifos.gr\/en\/%cf%80%cf%81%ce%bf%cf%83%ce%ba%ce%bb%ce%b7%cf%83%ce%b7-%ce%b5%ce%ba%ce%b4%ce%b7%ce%bb%cf%89%cf%83%ce%b7%cf%83-%ce%b5%ce%bd%ce%b4%ce%b9%ce%b1%cf%86%ce%b5%cf%81%ce%bf%ce%bd%cf%84%ce%bf%cf%83-%cf%85-28\/#listItem","name":"\u03a0\u03a1\u039f\u03a3\u039a\u039b\u0397\u03a3\u0397 \u0395\u039a\u0394\u0397\u039b\u03a9\u03a3\u0397\u03a3 \u0395\u039d\u0394\u0399\u0391\u03a6\u0395\u03a1\u039f\u039d\u03a4\u039f\u03a3 \u03a5\u03a0\u039f\u0392\u039f\u039b\u0397\u03a3 \u03a0\u03a1\u039f\u03a3\u03a6\u039f\u03a1\u03a9\u039d \u0393\u0399\u0391 \u03a4\u0397\u039d  \u03a0\u03a1\u039f\u039c\u0397\u0398\u0395\u0399\u0391 \u0395\u0399\u0394\u0399\u039a\u039f\u03a5 \u039b\u039f\u0393\u0399\u03a3\u039c\u0399\u039a\u039f\u03a5 SMART CITY BI  \u0393\u0399\u0391 \u039f\u0399\u039a\u039f\u039d\u039f\u039c\u0399\u039a\u0397 \u0394\u0399\u0391\u03a7\u0395\u0399\u03a1\u0399\u03a3\u0397."},"previousItem":{"@type":"ListItem","@id":"https:\/\/serifos.gr\/en#listItem","name":"Home"}},{"@type":"ListItem","@id":"https:\/\/serifos.gr\/en\/%cf%80%cf%81%ce%bf%cf%83%ce%ba%ce%bb%ce%b7%cf%83%ce%b7-%ce%b5%ce%ba%ce%b4%ce%b7%ce%bb%cf%89%cf%83%ce%b7%cf%83-%ce%b5%ce%bd%ce%b4%ce%b9%ce%b1%cf%86%ce%b5%cf%81%ce%bf%ce%bd%cf%84%ce%bf%cf%83-%cf%85-28\/#listItem","position":3,"name":"\u03a0\u03a1\u039f\u03a3\u039a\u039b\u0397\u03a3\u0397 \u0395\u039a\u0394\u0397\u039b\u03a9\u03a3\u0397\u03a3 \u0395\u039d\u0394\u0399\u0391\u03a6\u0395\u03a1\u039f\u039d\u03a4\u039f\u03a3 \u03a5\u03a0\u039f\u0392\u039f\u039b\u0397\u03a3 \u03a0\u03a1\u039f\u03a3\u03a6\u039f\u03a1\u03a9\u039d \u0393\u0399\u0391 \u03a4\u0397\u039d  \u03a0\u03a1\u039f\u039c\u0397\u0398\u0395\u0399\u0391 \u0395\u0399\u0394\u0399\u039a\u039f\u03a5 \u039b\u039f\u0393\u0399\u03a3\u039c\u0399\u039a\u039f\u03a5 SMART CITY BI  \u0393\u0399\u0391 \u039f\u0399\u039a\u039f\u039d\u039f\u039c\u0399\u039a\u0397 \u0394\u0399\u0391\u03a7\u0395\u0399\u03a1\u0399\u03a3\u0397.","previousItem":{"@type":"ListItem","@id":"https:\/\/serifos.gr\/en\/category\/%ce%b1%ce%bd%ce%b1%ce%ba%ce%bf%ce%b9%ce%bd%cf%8e%cf%83%ce%b5%ce%b9%cf%82\/#listItem","name":"\u0391\u03bd\u03b1\u03ba\u03bf\u03b9\u03bd\u03ce\u03c3\u03b5\u03b9\u03c2"}}]},{"@type":"Organization","@id":"https:\/\/serifos.gr\/en\/#organization","name":"Serifos.gr","description":"\u0399\u03c3\u03c4\u03bf\u03c3\u03b5\u03bb\u03af\u03b4\u03b1 \u0394\u03ae\u03bc\u03bf\u03c5 \u03a3\u03b5\u03c1\u03af\u03c6\u03bf\u03c5","url":"https:\/\/serifos.gr\/en\/","telephone":"+302281051210","logo":{"@type":"ImageObject","url":"https:\/\/serifos.gr\/wp-content\/uploads\/2017\/08\/Logo_final.png","@id":"https:\/\/serifos.gr\/en\/%cf%80%cf%81%ce%bf%cf%83%ce%ba%ce%bb%ce%b7%cf%83%ce%b7-%ce%b5%ce%ba%ce%b4%ce%b7%ce%bb%cf%89%cf%83%ce%b7%cf%83-%ce%b5%ce%bd%ce%b4%ce%b9%ce%b1%cf%86%ce%b5%cf%81%ce%bf%ce%bd%cf%84%ce%bf%cf%83-%cf%85-28\/#organizationLogo","width":181,"height":46},"image":{"@id":"https:\/\/serifos.gr\/en\/%cf%80%cf%81%ce%bf%cf%83%ce%ba%ce%bb%ce%b7%cf%83%ce%b7-%ce%b5%ce%ba%ce%b4%ce%b7%ce%bb%cf%89%cf%83%ce%b7%cf%83-%ce%b5%ce%bd%ce%b4%ce%b9%ce%b1%cf%86%ce%b5%cf%81%ce%bf%ce%bd%cf%84%ce%bf%cf%83-%cf%85-28\/#organizationLogo"},"sameAs":["https:\/\/www.facebook.com\/dimosserifou\/"]},{"@type":"Person","@id":"https:\/\/serifos.gr\/en\/author\/nslivanios\/#author","url":"https:\/\/serifos.gr\/en\/author\/nslivanios\/","name":"Stelios Livanios","image":{"@type":"ImageObject","@id":"https:\/\/serifos.gr\/en\/%cf%80%cf%81%ce%bf%cf%83%ce%ba%ce%bb%ce%b7%cf%83%ce%b7-%ce%b5%ce%ba%ce%b4%ce%b7%ce%bb%cf%89%cf%83%ce%b7%cf%83-%ce%b5%ce%bd%ce%b4%ce%b9%ce%b1%cf%86%ce%b5%cf%81%ce%bf%ce%bd%cf%84%ce%bf%cf%83-%cf%85-28\/#authorImage","url":"https:\/\/secure.gravatar.com\/avatar\/792605e3bbc86e998535857713ea857f9fd2f4916d59659513056a03e5d789f7?s=96&d=mm&r=g","width":96,"height":96,"caption":"Stelios Livanios"}},{"@type":"WebPage","@id":"https:\/\/serifos.gr\/en\/%cf%80%cf%81%ce%bf%cf%83%ce%ba%ce%bb%ce%b7%cf%83%ce%b7-%ce%b5%ce%ba%ce%b4%ce%b7%ce%bb%cf%89%cf%83%ce%b7%cf%83-%ce%b5%ce%bd%ce%b4%ce%b9%ce%b1%cf%86%ce%b5%cf%81%ce%bf%ce%bd%cf%84%ce%bf%cf%83-%cf%85-28\/#webpage","url":"https:\/\/serifos.gr\/en\/%cf%80%cf%81%ce%bf%cf%83%ce%ba%ce%bb%ce%b7%cf%83%ce%b7-%ce%b5%ce%ba%ce%b4%ce%b7%ce%bb%cf%89%cf%83%ce%b7%cf%83-%ce%b5%ce%bd%ce%b4%ce%b9%ce%b1%cf%86%ce%b5%cf%81%ce%bf%ce%bd%cf%84%ce%bf%cf%83-%cf%85-28\/","name":"\u03a0\u03a1\u039f\u03a3\u039a\u039b\u0397\u03a3\u0397 \u0395\u039a\u0394\u0397\u039b\u03a9\u03a3\u0397\u03a3 \u0395\u039d\u0394\u0399\u0391\u03a6\u0395\u03a1\u039f\u039d\u03a4\u039f\u03a3 \u03a5\u03a0\u039f\u0392\u039f\u039b\u0397\u03a3 \u03a0\u03a1\u039f\u03a3\u03a6\u039f\u03a1\u03a9\u039d \u0393\u0399\u0391 \u03a4\u0397\u039d \u03a0\u03a1\u039f\u039c\u0397\u0398\u0395\u0399\u0391 \u0395\u0399\u0394\u0399\u039a\u039f\u03a5 \u039b\u039f\u0393\u0399\u03a3\u039c\u0399\u039a\u039f\u03a5 SMART CITY BI \u0393\u0399\u0391 \u039f\u0399\u039a\u039f\u039d\u039f\u039c\u0399\u039a\u0397 \u0394\u0399\u0391\u03a7\u0395\u0399\u03a1\u0399\u03a3\u0397. - Serifos.gr","description":"\u03a0\u03c1\u03cc\u03c3\u03ba\u03bb\u03b7\u03c3\u03b7-SMART-CITY","inLanguage":"en-GB","isPartOf":{"@id":"https:\/\/serifos.gr\/en\/#website"},"breadcrumb":{"@id":"https:\/\/serifos.gr\/en\/%cf%80%cf%81%ce%bf%cf%83%ce%ba%ce%bb%ce%b7%cf%83%ce%b7-%ce%b5%ce%ba%ce%b4%ce%b7%ce%bb%cf%89%cf%83%ce%b7%cf%83-%ce%b5%ce%bd%ce%b4%ce%b9%ce%b1%cf%86%ce%b5%cf%81%ce%bf%ce%bd%cf%84%ce%bf%cf%83-%cf%85-28\/#breadcrumblist"},"author":{"@id":"https:\/\/serifos.gr\/en\/author\/nslivanios\/#author"},"creator":{"@id":"https:\/\/serifos.gr\/en\/author\/nslivanios\/#author"},"datePublished":"2021-07-30T10:11:12+03:00","dateModified":"2021-07-30T10:11:13+03:00"},{"@type":"WebSite","@id":"https:\/\/serifos.gr\/en\/#website","url":"https:\/\/serifos.gr\/en\/","name":"Serifos.gr","description":"\u0399\u03c3\u03c4\u03bf\u03c3\u03b5\u03bb\u03af\u03b4\u03b1 \u0394\u03ae\u03bc\u03bf\u03c5 \u03a3\u03b5\u03c1\u03af\u03c6\u03bf\u03c5","inLanguage":"en-GB","publisher":{"@id":"https:\/\/serifos.gr\/en\/#organization"}}]},"og:locale":"en_GB","og:site_name":"Serifos.gr - \u0399\u03c3\u03c4\u03bf\u03c3\u03b5\u03bb\u03af\u03b4\u03b1 \u0394\u03ae\u03bc\u03bf\u03c5 \u03a3\u03b5\u03c1\u03af\u03c6\u03bf\u03c5","og:type":"article","og:title":"\u03a0\u03a1\u039f\u03a3\u039a\u039b\u0397\u03a3\u0397 \u0395\u039a\u0394\u0397\u039b\u03a9\u03a3\u0397\u03a3 \u0395\u039d\u0394\u0399\u0391\u03a6\u0395\u03a1\u039f\u039d\u03a4\u039f\u03a3 \u03a5\u03a0\u039f\u0392\u039f\u039b\u0397\u03a3 \u03a0\u03a1\u039f\u03a3\u03a6\u039f\u03a1\u03a9\u039d \u0393\u0399\u0391 \u03a4\u0397\u039d \u03a0\u03a1\u039f\u039c\u0397\u0398\u0395\u0399\u0391 \u0395\u0399\u0394\u0399\u039a\u039f\u03a5 \u039b\u039f\u0393\u0399\u03a3\u039c\u0399\u039a\u039f\u03a5 SMART CITY BI \u0393\u0399\u0391 \u039f\u0399\u039a\u039f\u039d\u039f\u039c\u0399\u039a\u0397 \u0394\u0399\u0391\u03a7\u0395\u0399\u03a1\u0399\u03a3\u0397. - Serifos.gr","og:description":"\u03a0\u03c1\u03cc\u03c3\u03ba\u03bb\u03b7\u03c3\u03b7-SMART-CITY","og:url":"https:\/\/serifos.gr\/en\/%cf%80%cf%81%ce%bf%cf%83%ce%ba%ce%bb%ce%b7%cf%83%ce%b7-%ce%b5%ce%ba%ce%b4%ce%b7%ce%bb%cf%89%cf%83%ce%b7%cf%83-%ce%b5%ce%bd%ce%b4%ce%b9%ce%b1%cf%86%ce%b5%cf%81%ce%bf%ce%bd%cf%84%ce%bf%cf%83-%cf%85-28\/","og:image":"https:\/\/serifos.gr\/wp-content\/uploads\/2017\/08\/Logo_final.png","og:image:secure_url":"https:\/\/serifos.gr\/wp-content\/uploads\/2017\/08\/Logo_final.png","og:image:width":181,"og:image:height":46,"article:published_time":"2021-07-30T07:11:12+00:00","article:modified_time":"2021-07-30T07:11:13+00:00","article:publisher":"https:\/\/www.facebook.com\/dimosserifou\/","twitter:card":"summary","twitter:title":"\u03a0\u03a1\u039f\u03a3\u039a\u039b\u0397\u03a3\u0397 \u0395\u039a\u0394\u0397\u039b\u03a9\u03a3\u0397\u03a3 \u0395\u039d\u0394\u0399\u0391\u03a6\u0395\u03a1\u039f\u039d\u03a4\u039f\u03a3 \u03a5\u03a0\u039f\u0392\u039f\u039b\u0397\u03a3 \u03a0\u03a1\u039f\u03a3\u03a6\u039f\u03a1\u03a9\u039d \u0393\u0399\u0391 \u03a4\u0397\u039d \u03a0\u03a1\u039f\u039c\u0397\u0398\u0395\u0399\u0391 \u0395\u0399\u0394\u0399\u039a\u039f\u03a5 \u039b\u039f\u0393\u0399\u03a3\u039c\u0399\u039a\u039f\u03a5 SMART CITY BI \u0393\u0399\u0391 \u039f\u0399\u039a\u039f\u039d\u039f\u039c\u0399\u039a\u0397 \u0394\u0399\u0391\u03a7\u0395\u0399\u03a1\u0399\u03a3\u0397. - Serifos.gr","twitter:description":"\u03a0\u03c1\u03cc\u03c3\u03ba\u03bb\u03b7\u03c3\u03b7-SMART-CITY","twitter:image":"https:\/\/serifos.gr\/wp-content\/uploads\/2017\/08\/Logo_final.png"},"aioseo_meta_data":{"post_id":"5359","title":"#post_title #separator_sa #site_title","description":"#post_content","keywords":[],"keyphrases":{"focus":[],"additional":[]},"primary_term":null,"canonical_url":null,"og_title":null,"og_description":null,"og_object_type":"default","og_image_type":"default","og_image_url":null,"og_image_width":null,"og_image_height":null,"og_image_custom_url":null,"og_image_custom_fields":null,"og_video":"","og_custom_url":null,"og_article_section":null,"og_article_tags":[],"twitter_use_og":false,"twitter_card":"default","twitter_image_type":"default","twitter_image_url":null,"twitter_image_custom_url":null,"twitter_image_custom_fields":null,"twitter_title":null,"twitter_description":null,"schema":{"blockGraphs":[],"customGraphs":[],"default":{"data":{"Article":{"id":"#aioseo-article-65bbc867a0d2e","slug":"article","graphName":"Article","label":"Article","properties":{"type":"BlogPosting","name":"#post_title","headline":"#post_title","description":"#post_excerpt","image":"","keywords":"","author":{"name":"#author_name","url":"#author_url"},"dates":{"include":true,"datePublished":"","dateModified":""}}},"Course":[],"Dataset":[],"FAQPage":[],"Movie":[],"Person":[],"Product":[],"ProductReview":[],"Car":[],"Recipe":[],"Service":[],"SoftwareApplication":[],"WebPage":[]},"graphName":"Article","isEnabled":true},"graphs":[]},"schema_type":"default","schema_type_options":"{\"article\":{\"articleType\":\"BlogPosting\"},\"course\":{\"name\":\"\",\"description\":\"\",\"provider\":\"\"},\"faq\":{\"pages\":[]},\"product\":{\"reviews\":[]},\"recipe\":{\"ingredients\":[],\"instructions\":[],\"keywords\":[]},\"software\":{\"reviews\":[],\"operatingSystems\":[]},\"webPage\":{\"webPageType\":\"WebPage\"}}","pillar_content":false,"robots_default":true,"robots_noindex":false,"robots_noarchive":false,"robots_nosnippet":false,"robots_nofollow":false,"robots_noimageindex":false,"robots_noodp":false,"robots_notranslate":false,"robots_max_snippet":"-1","robots_max_videopreview":"-1","robots_max_imagepreview":"large","priority":null,"frequency":"default","local_seo":{"locations":{"business":{"name":"","businessType":"","image":"","areaServed":"","urls":{"website":"","aboutPage":"","contactPage":""},"address":{"streetLine1":"","streetLine2":"","zipCode":"","city":"","state":"","country":"","addressFormat":"#streetLineOne\n#streetLineTwo\n#city, #state #zipCode"},"contact":{"email":"","phone":"","phoneFormatted":"","fax":"","faxFormatted":""},"ids":{"vat":"","tax":"","chamberOfCommerce":""},"payment":{"priceRange":"","currenciesAccepted":"","methods":""}}},"openingHours":{"useDefaults":true,"show":true,"alwaysOpen":false,"use24hFormat":false,"timezone":"","labels":{"closed":"","alwaysOpen":""},"days":{"monday":{"open24h":false,"closed":false,"openTime":"09:00","closeTime":"17:00"},"tuesday":{"open24h":false,"closed":false,"openTime":"09:00","closeTime":"17:00"},"wednesday":{"open24h":false,"closed":false,"openTime":"09:00","closeTime":"17:00"},"thursday":{"open24h":false,"closed":false,"openTime":"09:00","closeTime":"17:00"},"friday":{"open24h":false,"closed":false,"openTime":"09:00","closeTime":"17:00"},"saturday":{"open24h":false,"closed":false,"openTime":"09:00","closeTime":"17:00"},"sunday":{"open24h":false,"closed":false,"openTime":"09:00","closeTime":"17:00"}}}},"breadcrumb_settings":null,"limit_modified_date":false,"ai":null,"created":"2021-07-30 07:10:41","updated":"2026-03-12 05:18:18","focus_keyword":null,"additional_keywords":null,"truseo_locale":null,"seo_analyzer_scan_date":null},"_links":{"self":[{"href":"https:\/\/serifos.gr\/en\/wp-json\/wp\/v2\/posts\/5359","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/serifos.gr\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/serifos.gr\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/serifos.gr\/en\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/serifos.gr\/en\/wp-json\/wp\/v2\/comments?post=5359"}],"version-history":[{"count":0,"href":"https:\/\/serifos.gr\/en\/wp-json\/wp\/v2\/posts\/5359\/revisions"}],"wp:attachment":[{"href":"https:\/\/serifos.gr\/en\/wp-json\/wp\/v2\/media?parent=5359"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/serifos.gr\/en\/wp-json\/wp\/v2\/categories?post=5359"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/serifos.gr\/en\/wp-json\/wp\/v2\/tags?post=5359"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}